{"id":3392,"date":"2015-02-07T02:06:51","date_gmt":"2015-02-07T07:06:51","guid":{"rendered":"https:\/\/www.adrianasbestrecipes.com\/?p=3392"},"modified":"2016-10-27T01:23:31","modified_gmt":"2016-10-27T05:23:31","slug":"chocolates-caseros-faciles","status":"publish","type":"post","link":"https:\/\/www.adrianasbestrecipes.com\/es\/chocolates-caseros-faciles\/","title":{"rendered":"Chocolates Caseros F\u00e1ciles"},"content":{"rendered":"<figure id=\"attachment_3393\" aria-describedby=\"caption-attachment-3393\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3393 size-full\" title=\"You can make easy homemade chocolates in just few minutes #ABRecipes\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes.jpg\" alt=\"You can make easy homemade chocolates in just few minutes #ABRecipes\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes.jpg 640w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes-560x420.jpg 560w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-3393\" class=\"wp-caption-text\">Puedes hacer estos chocolates caseros en unos minutos<\/figcaption><\/figure>\n<p>La fabricaci\u00f3n de chocolates es un arte, reconocidos chefs hacen del arte de la chocolater\u00eda una carrera. A la mayor\u00eda de la gente le encanta el chocolate y t\u00fa\u00a0puedes hacer chocolates caseros f\u00e1ciles en s\u00f3lo unos minutos. Esta es una idea sencilla\u00a0para hacer un regalo especial y para celebrar el d\u00eda de San Valent\u00edn.<\/p>\n<figure id=\"attachment_3394\" aria-describedby=\"caption-attachment-3394\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3394 size-full\" title=\"Ingredients for making easy homemade chocolates #ABRecipes\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Ingredients-for-making-easy-homemade-chocolates.jpg\" alt=\"Ingredients for making easy homemade chocolates #ABRecipes\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Ingredients-for-making-easy-homemade-chocolates.jpg 640w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Ingredients-for-making-easy-homemade-chocolates-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Ingredients-for-making-easy-homemade-chocolates-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Ingredients-for-making-easy-homemade-chocolates-560x420.jpg 560w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-3394\" class=\"wp-caption-text\">Ingredientes para preparar los chocolates caseros<\/figcaption><\/figure>\n<h2>INGREDIENTES<\/h2>\n<ul>\n<li>2 1\/2 tazas de chocolate blanco sabor vainilla<\/li>\n<li>1 taza de chocolate oscuro<\/li>\n<li>2 cucharaditas de pepitas<\/li>\n<li>2 cucharaditas de almendras<\/li>\n<\/ul>\n<p><strong><span style=\"text-decoration: underline;\"> Tiempo de preparaci\u00f3n:<\/span><\/strong> 30 minutos. Rinde para\u00a010 a 15 chocolates. El costo por pieza es menor a\u00a0$ 0.75 centavos dependiendo del costo de los ingredientes en tu supermercado local. Vas a necesitar\u00a0una bandeja, 2 bolsas de pl\u00e1stico, tazones para mezclar, cucharas y papel encerado.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/39miSp6JWQg?list=UUlUcYcFcBQKC8eWgspHdn2w\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Mira el video para que conozcas paso a paso c\u00f3mo hacer esta receta para preparar los chocolates caseros\u00a0o bien sigue estas instrucciones:<\/p>\n<p>1.- Inicia fundiendo primero el chocolate blanco en el microondas. Derrite los chocolates durante 30 segundos. Si hay necesidad de un poco\u00a0m\u00e1s de tiempo vuelve a colocar en el microondas por unos segundos m\u00e1s, pero ten cuidado de no quemar el chocolate.<br \/>\n2.- Vierte el chocolate derretido en una bolsa de pl\u00e1stico imitando una manga pastelera o conocida como duya.<br \/>\n3.- Coloca el papel encerado\u00a0en la bandeja, corta la punta de la bolsa y empieza a formar los chocolates haciendo remolinos.<br \/>\n4.- A continuaci\u00f3n, derrite el chocolate oscuro siguiendo las mismas instrucciones y roc\u00eda un poco de este chocolate oscuro sobre los chocolates blancos. A\u00f1ade las pepitas y las almendras y refrigera por 10 minutos.<br \/>\n5.- Coloca los chocolates en una bonita caja con papel de colores.<\/p>\n<figure id=\"attachment_3395\" aria-describedby=\"caption-attachment-3395\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3395 size-full\" title=\"Show you care with this easy homemade chocolates ready in 30 minutes #ABRecipes\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes.jpg\" alt=\"Show you care with this easy homemade chocolates ready in 30 minutes #ABRecipes\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes.jpg 640w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-560x420.jpg 560w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-3395\" class=\"wp-caption-text\">Muestra tu cari\u00f1o con un regalo hecho por ti como estos chocolates caseros<\/figcaption><\/figure>\n<p>Un regalo hecho con tus propias manos no s\u00f3lo expresa qu\u00e9 tan importante es\u00a0esa persona a qui\u00e9n le est\u00e1s obsequiando los chocolates, pero tambi\u00e9n demuestra el amor por la buena comida y en este caso el amor por los chocolates caseros f\u00e1ciles. Estos chocolates caseros f\u00e1ciles son ideales para regalar en cualquier ocasi\u00f3n como el d\u00eda de San Valent\u00edn, la <a title=\"Copitas de Pud\u00edn de Chocolate #ComidaKraft #ad\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/copitas-de-pudin-de-chocolate\/\">Navidad<\/a>, para un cumplea\u00f1os y para ofrecer como regalitos para bautizos o bodas.<\/p>\n<figure id=\"attachment_3396\" aria-describedby=\"caption-attachment-3396\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3396 size-full\" title=\"Easy Homemade Chocolates special gift idea for Valentines Day #ABRecipes\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Easy-Homemade-Chocolates-special-gift-idea-for-Valentines-Day.jpg\" alt=\"Easy Homemade Chocolates special gift idea for Valentines Day #ABRecipes\" width=\"640\" height=\"853\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Easy-Homemade-Chocolates-special-gift-idea-for-Valentines-Day.jpg 640w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Easy-Homemade-Chocolates-special-gift-idea-for-Valentines-Day-225x300.jpg 225w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Easy-Homemade-Chocolates-special-gift-idea-for-Valentines-Day-560x746.jpg 560w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-3396\" class=\"wp-caption-text\">Receta de Chocolates Caseros F\u00e1ciles lista en 30 Minutos<\/figcaption><\/figure>\n<p>Fabricaci\u00f3n de los chocolates en casa y poder hacerlos con los ni\u00f1os es tambi\u00e9n otra manera de participar con ellos y organizar actividades divertidas para introducirlos al gusto por la buena comida\u00a0y la cocina. Si te gustan las fresas te recomiendo esta receta f\u00e1cil para hacer <a title=\"Chocolate Covered Strawberries Recipe\" href=\"https:\/\/www.adrianasbestrecipes.com\/white-chocolate-strawberries\/\">fresas cubiertas de chocolate blanco<\/a>\u00a0tan populares durante el mes de febrero.<\/p>\n<p>Espero tengas un d\u00eda de San Valent\u00edn\u00a0muy feliz junto a todos tus seres queridos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Receta de chocolates caseros lista en menos de 30 minutos<\/p>\n","protected":false},"author":2,"featured_media":5713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Chocolates Caseros F\u00e1ciles","_seopress_titles_desc":"A la mayor\u00eda de la gente le encanta el chocolate y t\u00fa puedes hacer chocolates caseros f\u00e1ciles en s\u00f3lo unos minutos.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Chocolates Caseros","_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[73,70],"tags":[],"class_list":["post-3392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-facil-y-rapido","category-postres","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_featured_media_url":"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg","spectra_custom_meta":{"_edit_lock":["1477545813:2"],"_edit_last":["2"],"_alp_processed":["1477545813"],"image":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/You-can-make-easy-homemade-chocolates-in-just-few-minutes.jpg"],"pinType":["movie"],"pinName":[""],"pinDescription":[""],"pinRating":[""],"pinRatingMax":[""],"pinContent":["G"],"pinDate":[""],"numDirectors":["0"],"numActors":["0"],"_yoast_wpseo_focuskw":["Chocolates Caseros"],"_yoast_wpseo_linkdex":["79"],"_yoast_wpseo_metadesc":["A la mayor\u00eda de la gente le encanta el chocolate y t\u00fa puedes hacer chocolates caseros f\u00e1ciles en s\u00f3lo unos minutos."],"_image_alignment":["c"],"dsq_thread_id":["3493273550"],"_yoast_wpseo_title":["Chocolates Caseros F\u00e1ciles"],"_thumbnail_id":["5713"],"_et_social_shares_facebook":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-08-24 22:17:04\";}"],"_et_social_shares_twitter":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-08-24 22:17:04\";}"],"_et_social_shares_googleplus":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-08-24 22:17:05\";}"],"_et_social_shares_pinterest":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-08-24 22:17:06\";}"],"_et_social_shares_delicious":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-05-26 21:10:26\";}"],"_et_social_shares_digg":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-05-26 21:10:26\";}"],"_et_social_shares_printfriendly":["a:3:{s:12:\"force_update\";b:1;s:6:\"counts\";i:0;s:8:\"last_upd\";s:19:\"2016-08-24 22:17:06\";}"],"_totes":["0"],"bitly_link":["http:\/\/bit.ly\/2GTkANk"],"_facebook_shares":["0"],"_twitter_shares":["0"],"_pinterest_shares":["0"],"_yummly_shares":["0"],"_whatsapp_shares":["0"],"_google_plus_shares":["0"],"_total_shares":["0"],"swp_pinterest_image_url":[""],"bitly_link_google_plus":["http:\/\/bit.ly\/2MsyF9Q"],"bitly_link_facebook":["http:\/\/bit.ly\/2vFUbOZ"],"bitly_link_twitter":["http:\/\/bit.ly\/2MsyDPg"],"bitly_link_whatsapp":["http:\/\/bit.ly\/2vFEqaz"],"bitly_link_yummly":["http:\/\/bit.ly\/2Mlxau7"],"swp_cache_timestamp":["428625"],"dpsp_networks_shares":["a:7:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;s:4:\"grow\";i:1;}"],"dpsp_networks_shares_total":["1"],"dpsp_networks_shares_last_updated":["1643589480"],"dpsp_cache_shares_twitter_2":["0"],"dpsp_short_link_bitly":["a:14:{s:18:\"facebook_short_url\";s:21:\"http:\/\/bit.ly\/2uwPBld\";s:17:\"twitter_short_url\";s:21:\"http:\/\/bit.ly\/2uxwwzf\";s:18:\"whatsapp_short_url\";s:21:\"http:\/\/bit.ly\/2uwPBBJ\";s:16:\"yummly_short_url\";s:21:\"http:\/\/bit.ly\/2uwPBSf\";s:15:\"email_short_url\";s:21:\"http:\/\/bit.ly\/2uBo424\";s:13:\"mix_short_url\";s:21:\"http:\/\/bit.ly\/2OOy1nX\";s:19:\"flipboard_short_url\";s:21:\"http:\/\/bit.ly\/2MHShVJ\";s:18:\"linkedin_short_url\";s:21:\"http:\/\/bit.ly\/2BcHYUf\";s:16:\"reddit_short_url\";s:21:\"http:\/\/bit.ly\/2plhWM0\";s:16:\"buffer_short_url\";s:21:\"http:\/\/bit.ly\/2pn4ffo\";s:18:\"telegram_short_url\";s:21:\"http:\/\/bit.ly\/2OMfJDX\";s:14:\"grow_short_url\";s:22:\"https:\/\/bit.ly\/2PUdK3h\";s:17:\"threads_short_url\";s:22:\"https:\/\/bit.ly\/3xhzlsl\";s:18:\"mastodon_short_url\";s:22:\"https:\/\/bit.ly\/4bb7Puk\";}"],"_jetpack_related_posts_cache":["a:1:{s:32:\"8f6677c9d6b0f903e98ad32ec61f8deb\";a:2:{s:7:\"expires\";i:1622148372;s:7:\"payload\";a:3:{i:0;a:1:{s:2:\"id\";i:2947;}i:1;a:1:{s:2:\"id\";i:1880;}i:2;a:1:{s:2:\"id\";i:3561;}}}}"],"dpsp_post_previous_urls":["a:1:{i:0;s:77:\"https:\/\/www.adrianasbestrecipes.com\/es\/2015\/02\/07\/chocolates-caseros-faciles\/\";}"],"dpsp_networks_shares_previous_urls":["a:6:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;}"],"_tbf_fix_details":["a:5:{s:6:\"fix_id\";s:2:\"37\";s:19:\"changed_revision_id\";s:4:\"3392\";s:20:\"original_revision_id\";s:4:\"3392\";s:17:\"operation_set_ids\";s:15:\"link_target_fix\";s:10:\"operations\";a:1:{i:0;s:18:\"regex_link_replace\";}}"],"_wpml_media_duplicate":["1"],"_yoast_wpseo_video_meta":["a:16:{s:2:\"id\";s:11:\"39miSp6JWQg\";s:3:\"url\";s:71:\"https:\/\/www.youtube.com\/embed\/39miSp6JWQg?list=UUlUcYcFcBQKC8eWgspHdn2w\";s:4:\"type\";s:7:\"youtube\";s:10:\"player_loc\";s:41:\"https:\/\/www.youtube.com\/embed\/39miSp6JWQg\";s:13:\"thumbnail_loc\";s:80:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/39misp6jwqg-1.jpg\";s:12:\"last_fetched\";i:1676365979;s:8:\"duration\";i:66;s:10:\"view_count\";s:3:\"219\";s:5:\"width\";i:480;s:6:\"height\";i:270;s:7:\"post_id\";i:3392;s:5:\"title\";s:27:\"Chocolates Caseros F\u00e1ciles\";s:16:\"publication_date\";s:25:\"2015-02-07T07:06:51+00:00\";s:11:\"description\";s:119:\"A la mayor\u00eda de la gente le encanta el chocolate y t\u00fa puedes hacer chocolates caseros f\u00e1ciles en s\u00f3lo unos minutos.\";s:8:\"category\";s:16:\"F\u00e1cil y R\u00e1pido\";s:3:\"tag\";a:1:{i:0;s:18:\"Chocolates Caseros\";}}"],"litespeed_vpi_list":["a:3:{i:0;s:37:\"ABRecipes-New-Logo-with-Trademark.jpg\";i:1;s:74:\"Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg\";i:2;s:36:\"Adriana-Martin-TACOS-23-683x1024.jpg\";}"],"_seopress_titles_title":["Chocolates Caseros F\u00e1ciles"],"_seopress_titles_desc":["A la mayor\u00eda de la gente le encanta el chocolate y t\u00fa puedes hacer chocolates caseros f\u00e1ciles en s\u00f3lo unos minutos."],"_seopress_analysis_target_kw":["Chocolates Caseros"],"dpsp_networks_shares_json":["{\"facebook\":0,\"twitter\":0,\"pinterest\":0,\"yummly\":0,\"reddit\":0,\"buffer\":0,\"grow\":1}"],"wprm_rating_no_text_comments":["a:0:{}"],"copied_media_ids":["a:4:{i:0;i:219720;i:1;i:219721;i:2;i:219722;i:3;i:219723;}"],"referenced_media_ids":["a:1:{i:0;i:5713;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:0:{}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778691283\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-180x180.jpg",180,180,true],"medium":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"1536x1536":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"2048x2048":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"wprm-metadata-1_1":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-500x480.jpg",500,480,true],"wprm-metadata-4_3":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-480x270.jpg",480,270,true],"rpwe-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-45x45.jpg",45,45,true],"mailchimp":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1-560x420.jpg",560,420,true],"web-stories-poster-portrait":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Show-you-care-with-this-easy-homemade-chocolates-ready-in-30-minutes-1.jpg",150,113,false]},"uagb_author_info":{"display_name":"Chef Adriana Martin","author_link":"https:\/\/www.adrianasbestrecipes.com\/es\/author\/adriana\/"},"uagb_comment_info":0,"uagb_excerpt":"Receta de chocolates caseros lista en menos de 30 minutos","jetpack-related-posts":[{"id":8859,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/trufas-de-chocolate-y-cacahuate\/","url_meta":{"origin":3392,"position":0},"title":"Trufas de Chocolate y Cacahuate","author":"Chef Adriana Martin","date":"22 de septiembre de 2016","format":false,"excerpt":"\u00a1Hicimos trufas de chocolate y cacahuate, una receta para bombones caseros apta para los ni\u00f1os! Estas trufas son uno de los postres f\u00e1ciles de la infancia.","rel":"","context":"En \u00abPostres y Panader\u00eda\u00bb","block_context":{"text":"Postres y Panader\u00eda","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/postres\/"},"img":{"alt_text":"Estas son las trufas chocolate y cacahuate mismas que tienen leche condensada, avena, chocolate en polvo, hojuelas de coco, mantequilla de man\u00ed y chispas de chocolate.","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/05\/Mexican-Chocolate-Peanut-Truffles-recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/05\/Mexican-Chocolate-Peanut-Truffles-recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/05\/Mexican-Chocolate-Peanut-Truffles-recipe.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/05\/Mexican-Chocolate-Peanut-Truffles-recipe.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37975,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/panecillos-caseros-de-calabaza\/","url_meta":{"origin":3392,"position":1},"title":"Panecillos Caseros de Calabaza","author":"Chef Adriana Martin","date":"30 de noviembre de 2020","format":false,"excerpt":"La temporada de calabazas nos invita a preparar panecillos caseros tambi\u00e9n llamados bollitos de calabaza. Una receta f\u00e1cil para principiantes.","rel":"","context":"En \u00abPostres y Panader\u00eda\u00bb","block_context":{"text":"Postres y Panader\u00eda","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/postres\/"},"img":{"alt_text":"Una bandeja con Panecillos Caseros de Calabaza","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/11\/Pumpkin-Dinner-Rolls.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/11\/Pumpkin-Dinner-Rolls.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/11\/Pumpkin-Dinner-Rolls.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2020\/11\/Pumpkin-Dinner-Rolls.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12882,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/ensalada-de-frambuesas-y-pollo-asado\/","url_meta":{"origin":3392,"position":2},"title":"Ensalada de Frambuesas y Pollo Asado","author":"Chef Adriana Martin","date":"29 de abril de 2017","format":false,"excerpt":"Ensalada de frambuesas y pollo asado con aderezo casero picante de Sriracha. Una opci\u00f3n f\u00e1cil y lista en cuesti\u00f3n de minutos.","rel":"","context":"En \u00abAlmuerzo\u00bb","block_context":{"text":"Almuerzo","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/almuerzo-es\/"},"img":{"alt_text":"Ensalada de frambuesas y pollo asado con aderezo picante de Sriracha","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Sriracha-Raspberry-Chicken-Salad-Recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Sriracha-Raspberry-Chicken-Salad-Recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Sriracha-Raspberry-Chicken-Salad-Recipe.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Sriracha-Raspberry-Chicken-Salad-Recipe.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29306,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/yogurt-casero-al-estilo-instant-pot\/","url_meta":{"origin":3392,"position":3},"title":"Yogurt Casero al Estilo Instant Pot","author":"Chef Adriana Martin","date":"17 de septiembre de 2019","format":false,"excerpt":"Esta es la receta cl\u00e1sica para del Yogurt Casero adaptada para el Instant Pot. Requiere solo tres ingredientes y el resultado es fant\u00e1stico.","rel":"","context":"En \u00abDesayuno\u00bb","block_context":{"text":"Desayuno","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/desayuno-breakfast\/"},"img":{"alt_text":"Yogurt Casero al Estilo Instant Pot servido con miel de abeja y frutas frescas","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2019\/08\/Recipe-for-the-Instant-Pot-Yogurt-Mexican-Style.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2019\/08\/Recipe-for-the-Instant-Pot-Yogurt-Mexican-Style.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2019\/08\/Recipe-for-the-Instant-Pot-Yogurt-Mexican-Style.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2019\/08\/Recipe-for-the-Instant-Pot-Yogurt-Mexican-Style.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":40792,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pozol-una-bebida-autentica-mexicana\/","url_meta":{"origin":3392,"position":4},"title":"Pozol, Una Bebida Aut\u00e9ntica Mexicana","author":"Chef Adriana Martin","date":"14 de septiembre de 2021","format":false,"excerpt":"\u00a1El pozol o pochotl es una bebida prehisp\u00e1nica con cacao y masa de ma\u00edz s\u00faper f\u00e1cil de preparar!","rel":"","context":"En \u00abBebidas y Cocteles\u00bb","block_context":{"text":"Bebidas y Cocteles","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/beverages-es\/"},"img":{"alt_text":"Two bowls of pozol made with cacao and corn masa","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2021\/08\/Two-bowls-of-pozol-made-with-cacao-and-corn-masa.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2021\/08\/Two-bowls-of-pozol-made-with-cacao-and-corn-masa.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2021\/08\/Two-bowls-of-pozol-made-with-cacao-and-corn-masa.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2021\/08\/Two-bowls-of-pozol-made-with-cacao-and-corn-masa.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2021\/08\/Two-bowls-of-pozol-made-with-cacao-and-corn-masa.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3413,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pastelillos-de-fresa-y-chocolate\/","url_meta":{"origin":3392,"position":5},"title":"Pastelillos de Fresa y Chocolate","author":"Chef Adriana Martin","date":"13 de febrero de 2015","format":false,"excerpt":"Pastelillos de Fresa y Chocolate, hechos con amor!","rel":"","context":"En \u00abPostres y Panader\u00eda\u00bb","block_context":{"text":"Postres y Panader\u00eda","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/postres\/"},"img":{"alt_text":"Strawberry Chocolate cupcakes made with fresh from Florida strawberries","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Strawberry-Chocolate-cupcakes-made-with-fresh-from-Florida-strawberries-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Strawberry-Chocolate-cupcakes-made-with-fresh-from-Florida-strawberries-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Strawberry-Chocolate-cupcakes-made-with-fresh-from-Florida-strawberries-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/3392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/comments?post=3392"}],"version-history":[{"count":0,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/3392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media\/5713"}],"wp:attachment":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media?parent=3392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/categories?post=3392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/tags?post=3392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}