{"id":2602,"date":"2014-06-03T22:41:27","date_gmt":"2014-06-04T02:41:27","guid":{"rendered":"https:\/\/www.adrianasbestrecipes.com\/?p=2602"},"modified":"2014-06-09T12:49:51","modified_gmt":"2014-06-09T16:49:51","slug":"celebrando-la-fiebre-del-soccer-comidakraft","status":"publish","type":"post","link":"https:\/\/www.adrianasbestrecipes.com\/es\/celebrando-la-fiebre-del-soccer-comidakraft\/","title":{"rendered":"Celebrando la Fiebre del Soccer #ComidaKraft"},"content":{"rendered":"<p><i>Este art\u00edculo es tra\u00eddo en colaboraci\u00f3n con <a title=\"Site Comida Kraft\" href=\"http:\/\/www.comidakraft.com\/sp\/sabores\/default.aspx\" target=\"_blank\" rel=\"nofollow\"><strong>Comida Kraft<\/strong> <\/a>sin embargo todas las opiniones son m\u00edas.<\/i><\/p>\n<p class=\"p1\">Estoy muy contenta en\u00a0anunciar oficialmente que soy parte de la campa\u00f1a \"Amigas de Comida Kraft \", en donde voy a compartir deliciosas recetas preparadas con la amplia y sabrosa familia de productos Kraft. Mi primera receta celebra los sabores latinos para empezar celebrando la fiebre del soccer. Como buena mexicana me encantan los juegos de f\u00fatbol y m\u00e1s cuando son a nivel internacional como son los\u00a0juegos del Campeonato. Tengo tantos lindos recuerdos de cuando compart\u00edamos con la familia en M\u00e9xico mientras ayudaba a mi mam\u00e1 y a mi abuela a preparar botanas variadas\u00a0y\u00a0<strong><a title=\"Comida Kraft Sitio de Recetas\" href=\"http:\/\/www.comidakraft.com\/sp\/sabores\/default.aspx\" target=\"_blank\" rel=\"nofollow\"><span class=\"s2\">recetas de guacamole<\/span><\/a><\/strong>, que eran nuestras favoritas entre otras delicias, como chorizo espa\u00f1ol cortado en rodajitas, taquitos dorados y aceitunas espa\u00f1olas deliciosamente sazonadas con jugo de lim\u00f3n, salsa inglesa y salsa tabasco nada mas de acordarme se me hace agua la boca.<\/p>\n<figure id=\"attachment_2628\" aria-describedby=\"caption-attachment-2628\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.comidakraft.com\/sp\/recipes\/dip-picante-de-aguacate-con-queso-crema-philadelphia-cream-cheese-165473.aspx\" target=\"_blank\" rel=\"attachment wp-att-2628\"><img decoding=\"async\" class=\"wp-image-2628\" title=\"KRAFT Ingredients for Spicy Avocado Dip with PHILADELPHIA Cream Cheese\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Ingredients-for-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese.jpg\" alt=\"KRAFT Ingredients for Spicy Avocado Dip with PHILADELPHIA Cream Cheese\" width=\"645\" height=\"484\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Ingredients-for-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese.jpg 645w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Ingredients-for-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Ingredients-for-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Ingredients-for-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-560x420.jpg 560w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/a><figcaption id=\"caption-attachment-2628\" class=\"wp-caption-text\">Ingredientses KRAFT para preparar el Dip Picante de Aguacate con Queso Crema PHILADELPHIA Cream Cheese. Dale clic a la foto para ver la receta.<\/figcaption><\/figure>\n<p class=\"p1\">Tomando como inspiraci\u00f3n la receta de guacamole de mi mam\u00e1 y la que disfrut\u00e1bamos tanto en\u00a0mi familia he creado para Amigas de Comida Kraft un <strong><a title=\"Receta del Dip Picante de Aguacate y queso PHILADELPHIA Cream Cheese\" href=\"http:\/\/www.comidakraft.com\/sp\/recipes\/dip-picante-de-aguacate-con-queso-crema-philadelphia-cream-cheese-165473.aspx\" target=\"_blank\" rel=\"nofollow\">Dip Picante de Aguacate con queso crema PHILADELPHIA Cream Cheese<\/a><\/strong>, perfecto para disfrutar viendo los partidos y animando a tu equipo favorito. Para hacer esta \u00e9poca de los juegos m\u00e1s divertida Kraft tambi\u00e9n invita a todos los aficionados al f\u00fatbol a suscribirse gratuitamente al sitio de Recetas de Comida Kraft por correo electr\u00f3nico para\u00a0<strong><a title=\"Ringtones Futboleros en Comida Kraft\" href=\"http:\/\/www.comidakraft.com\/sp\/sabores\/ringtones-futboleros.aspx?promo_id=2014_Ring_module_sabores\" target=\"_blank\" rel=\"nofollow\">bajar ringtones futboleros<\/a><\/strong>.<\/p>\n<figure id=\"attachment_2629\" aria-describedby=\"caption-attachment-2629\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.comidakraft.com\/sp\/recipes\/dip-picante-de-aguacate-con-queso-crema-philadelphia-cream-cheese-165473.aspx\" target=\"_blank\" rel=\"attachment wp-att-2629\"><img decoding=\"async\" class=\"wp-image-2629\" title=\"Spicy Avocado Dip with PHILADELPHIA Cream Cheese A Golazo to the Tastebuds\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-A-Golazo-to-the-Tastebuds.jpg\" alt=\"Spicy Avocado Dip with PHILADELPHIA Cream Cheese A Golazo to the Tastebuds\" width=\"645\" height=\"484\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-A-Golazo-to-the-Tastebuds.jpg 645w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-A-Golazo-to-the-Tastebuds-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-A-Golazo-to-the-Tastebuds-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-A-Golazo-to-the-Tastebuds-560x420.jpg 560w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/a><figcaption id=\"caption-attachment-2629\" class=\"wp-caption-text\">Dip Picante de Aguacte y Queso Crema PHILADELPHIA Cream Cheese un Golazo de Sabor. Dale clic a la imagen para ver la receta.<\/figcaption><\/figure>\n<p class=\"p1\">En tan s\u00f3lo unos d\u00edas todos vamos a estar viendo los juegos y disfrutar del esp\u00edritu del Campeonato. No importa si es en casa, en la oficina o con amigos pero los juego se disfrutan a\u00fan m\u00e1s con bocadillos deliciosos y una forma de tener ideas de recetas f\u00e1ciles \u00e9stas las puedes encontrar en el <strong><a title=\"Sitio de Recetas de Comida Kraft\" href=\"http:\/\/www.comidakraft.com\/sp\/sabores\/default.aspx\" target=\"_blank\" rel=\"nofollow\">Hub de Recetas de\u00a0Kraft <\/a><\/strong>para que lleves los Sabores del Campeonato donde quiera que est\u00e9s.<\/p>\n<figure id=\"attachment_2630\" aria-describedby=\"caption-attachment-2630\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.comidakraft.com\/sp\/recipes\/dip-picante-de-aguacate-con-queso-crema-philadelphia-cream-cheese-165473.aspx\" target=\"_blank\" rel=\"attachment wp-att-2630\"><img decoding=\"async\" class=\"wp-image-2630\" title=\"KRAFT Spicy Avocado Dip with PHILADELPHIA Cream Cheese\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese.jpg\" alt=\"KRAFT Spicy Avocado Dip with PHILADELPHIA Cream Cheese\" width=\"645\" height=\"484\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese.jpg 645w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-560x420.jpg 560w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/a><figcaption id=\"caption-attachment-2630\" class=\"wp-caption-text\">Dip Picante de Aguacate con queso crema PHILADELPHIA Cream Cheese<\/figcaption><\/figure>\n<p>Los invito a seguir mis recetas en Amigas de Comida Kraft \u00a0en donde estar\u00e9 publicando\u00a0recetas sabrosas, \u00a0f\u00e1ciles de hacer y usando los productos de Kraft que a todo el mundo gustan.<\/p>\n<p>\u00a1Celebremos la fiesta del F\u00fatbol con los Sabores del Campeonato y Comida Kraft y de esa forma anotar un gol con la familia!<\/p>\n<figure id=\"attachment_2627\" aria-describedby=\"caption-attachment-2627\" style=\"width: 290px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.comidakraft.com\/sp\/Community\/amigas-de-comidakraft\/adriana-martin\/main.aspx\" target=\"_blank\" rel=\"attachment wp-att-2627\"><img decoding=\"async\" class=\"wp-image-2627 size-medium\" title=\"Amigas de Comida Kraft\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-300x300.png\" alt=\"Amigas de Comida Kraft\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-300x300.png 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-180x180.png 180w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-500x500.png 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-45x45.png 45w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-560x560.png 560w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-400x400.png 400w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1-125x125.png 125w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/Comida-Kraft_ambassador-badge-1.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-2627\" class=\"wp-caption-text\">Celebrando la Fiebre del Soccer con Comida Kraft<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Celebra los partidos de f\u00fatbol con los sabores del campeonato!<\/p>\n","protected":false},"author":2,"featured_media":5815,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"Los campeonatos de f\u00fatbol son una buena excusa para reunirse y disfrutar en familia platillos caseros. Celebrando la Fiebre del Soccer con Comida Kraft.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Celebrando la Fiebre del Soccer","_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[73],"tags":[1674,570,1675,61,1676,1673],"class_list":["post-2602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-facil-y-rapido","tag-comida-kraft","tag-destacado","tag-dip-picante-de-aguacate","tag-espanol","tag-philadelphia-cream-cheese-es","tag-soccer-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_featured_media_url":"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg","spectra_custom_meta":{"_edit_lock":["1402333506:2"],"_edit_last":["2"],"_alp_processed":["1402332592"],"image":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese.jpg"],"pinType":["movie"],"pinName":[""],"pinDescription":[""],"pinRating":[""],"pinRatingMax":[""],"pinContent":["G"],"pinDate":[""],"numDirectors":["0"],"numActors":["0"],"_yoast_wpseo_focuskw":["Celebrando la Fiebre del Soccer"],"_yoast_wpseo_linkdex":["78"],"_yoast_wpseo_metadesc":["Los campeonatos de f\u00fatbol son una buena excusa para reunirse y disfrutar en familia platillos caseros. Celebrando la Fiebre del Soccer con Comida Kraft."],"_yoast_wpseo_meta-robots-nofollow":["1"],"_image_alignment":["c"],"dsq_thread_id":["2734438981"],"_thumbnail_id":["5815"],"bitly_link":["http:\/\/bit.ly\/2E690Qe"],"bitly_link_facebook":["http:\/\/bit.ly\/2L1Xhl4"],"bitly_link_twitter":["http:\/\/bit.ly\/2L1XqF8"],"bitly_link_whatsapp":["http:\/\/bit.ly\/2L1XjJI"],"bitly_link_yummly":["http:\/\/bit.ly\/2OFbMO4"],"bitly_link_google_plus":["http:\/\/bit.ly\/2OCQ3q8"],"swp_pinterest_image_url":[""],"swp_cache_timestamp":["427573"],"dpsp_networks_shares":["a:7:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;s:4:\"grow\";i:1;}"],"dpsp_networks_shares_total":["1"],"dpsp_networks_shares_last_updated":["1642343980"],"dpsp_cache_shares_twitter_2":["0"],"dpsp_short_link_bitly":["a:14:{s:18:\"facebook_short_url\";s:21:\"http:\/\/bit.ly\/2uC70c1\";s:17:\"twitter_short_url\";s:21:\"http:\/\/bit.ly\/2uyjtO1\";s:18:\"whatsapp_short_url\";s:21:\"http:\/\/bit.ly\/2uBMEj6\";s:16:\"yummly_short_url\";s:21:\"http:\/\/bit.ly\/2uzLAfJ\";s:15:\"email_short_url\";s:21:\"http:\/\/bit.ly\/2uBMCru\";s:13:\"mix_short_url\";s:21:\"http:\/\/bit.ly\/33PY2Yt\";s:19:\"flipboard_short_url\";s:21:\"http:\/\/bit.ly\/2p0A5ij\";s:18:\"linkedin_short_url\";s:21:\"http:\/\/bit.ly\/33VDu0P\";s:16:\"reddit_short_url\";s:21:\"http:\/\/bit.ly\/2MUHbN7\";s:16:\"buffer_short_url\";s:21:\"http:\/\/bit.ly\/31wPdkw\";s:18:\"telegram_short_url\";s:21:\"http:\/\/bit.ly\/32wnUIA\";s:14:\"grow_short_url\";s:22:\"https:\/\/bit.ly\/33sd741\";s:17:\"threads_short_url\";s:22:\"https:\/\/bit.ly\/3z7qUjV\";s:18:\"mastodon_short_url\";s:22:\"https:\/\/bit.ly\/3xn1QVA\";}"],"_jetpack_related_posts_cache":["a:1:{s:32:\"8f6677c9d6b0f903e98ad32ec61f8deb\";a:2:{s:7:\"expires\";i:1622281376;s:7:\"payload\";a:3:{i:0;a:1:{s:2:\"id\";i:3385;}i:1;a:1:{s:2:\"id\";i:2766;}i:2;a:1:{s:2:\"id\";i:4247;}}}}"],"dpsp_post_previous_urls":["a:1:{i:0;s:94:\"https:\/\/www.adrianasbestrecipes.com\/es\/2014\/06\/03\/celebrando-la-fiebre-del-soccer-comidakraft\/\";}"],"dpsp_networks_shares_previous_urls":["a:5:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;}"],"litespeed_vpi_list":["a:3:{i:0;s:37:\"ABRecipes-New-Logo-with-Trademark.jpg\";i:1;s:60:\"KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg\";i:2;s:36:\"Adriana-Martin-TACOS-23-683x1024.jpg\";}"],"_seopress_titles_desc":["Los campeonatos de f\u00fatbol son una buena excusa para reunirse y disfrutar en familia platillos caseros. Celebrando la Fiebre del Soccer con Comida Kraft."],"_seopress_robots_follow":["yes"],"_seopress_analysis_target_kw":["Celebrando la Fiebre del Soccer"],"dpsp_networks_shares_json":["{\"facebook\":0,\"twitter\":0,\"pinterest\":0,\"yummly\":0,\"reddit\":0,\"buffer\":0,\"grow\":1}"],"wprm_rating_no_text_comments":["a:0:{}"],"copied_media_ids":["a:4:{i:0;i:219293;i:1;i:219294;i:2;i:219295;i:3;i:219292;}"],"referenced_media_ids":["a:1:{i:0;i:5815;}"],"_tbf_fix_details":["a:5:{s:6:\"fix_id\";s:4:\"5097\";s:19:\"changed_revision_id\";s:4:\"2602\";s:20:\"original_revision_id\";s:4:\"2602\";s:17:\"operation_set_ids\";s:36:\"images_performance_and_seo_optimizer\";s:10:\"operations\";a:1:{i:0;s:11:\"tag_replace\";}}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:0:{}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778703422\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",645,484,false],"thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-180x180.jpg",180,180,true],"medium":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",645,484,false],"large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",645,484,false],"1536x1536":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",645,484,false],"2048x2048":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",645,484,false],"wprm-metadata-1_1":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-500x484.jpg",500,484,true],"wprm-metadata-4_3":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-480x270.jpg",480,270,true],"rpwe-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-45x45.jpg",45,45,true],"mailchimp":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1-560x420.jpg",560,420,true],"web-stories-poster-portrait":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/06\/KRAFT-Spicy-Avocado-Dip-with-PHILADELPHIA-Cream-Cheese-1.jpg",150,113,false]},"uagb_author_info":{"display_name":"Chef Adriana Martin","author_link":"https:\/\/www.adrianasbestrecipes.com\/es\/author\/adriana\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a1Celebra los partidos de f\u00fatbol con los sabores del campeonato!","jetpack-related-posts":[{"id":2766,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/goza-el-verano-con-recetas-faciles-comidakraft-ad\/","url_meta":{"origin":2602,"position":0},"title":"\u00a1Goza el Verano con Recetas F\u00e1ciles! #ComidaKraft #ad","author":"Chef Adriana Martin","date":"4 de agosto de 2014","format":false,"excerpt":"El verano invita a preparar recetas f\u00e1ciles para evadir el calor de la cocina.","rel":"","context":"En \u00abF\u00e1cil y R\u00e1pido\u00bb","block_context":{"text":"F\u00e1cil y R\u00e1pido","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/facil-y-rapido\/"},"img":{"alt_text":"Grilled-Shrimp-Tacos-with-KRAFT-Classic-Ranch-Dressing-part-of-the-Summer-easy-recipes","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/08\/Grilled-Shrimp-Tacos-with-KRAFT-Classic-Ranch-Dressing-part-of-the-Summer-easy-recipes-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/08\/Grilled-Shrimp-Tacos-with-KRAFT-Classic-Ranch-Dressing-part-of-the-Summer-easy-recipes-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/08\/Grilled-Shrimp-Tacos-with-KRAFT-Classic-Ranch-Dressing-part-of-the-Summer-easy-recipes-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2878,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/celebrando-la-herencia-hispana\/","url_meta":{"origin":2602,"position":1},"title":"Celebrando la Herencia Hispana","author":"Chef Adriana Martin","date":"2 de septiembre de 2014","format":false,"excerpt":"Celebremos nuestra Herencia Hispana y el mes del aguacate con ricas recetas","rel":"","context":"En \u00abAlmuerzo\u00bb","block_context":{"text":"Almuerzo","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/almuerzo-es\/"},"img":{"alt_text":"Avocado Soup with Poblanos Cheese and Roasted Veggies #ComidaKraft #Ad","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/09\/Avocado-Soup-with-Poblanos-Cheese-and-Roasted-Veggies-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/09\/Avocado-Soup-with-Poblanos-Cheese-and-Roasted-Veggies-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/09\/Avocado-Soup-with-Poblanos-Cheese-and-Roasted-Veggies-.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4031,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/gelatina-tropical-con-jell-o-melon-y-pina-fresca\/","url_meta":{"origin":2602,"position":2},"title":"Gelatina Tropical con JELL-O, Mel\u00f3n y Pi\u00f1a Fresca","author":"Chef Adriana Martin","date":"7 de julio de 2015","format":false,"excerpt":"Una opci\u00f3n fresca y ligera","rel":"","context":"En \u00abQuick and Easy\u00bb","block_context":{"text":"Quick and Easy","link":"https:\/\/www.adrianasbestrecipes.com\/category\/quick-easy\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/07\/Tropical-Melon-Jello-Dessert-Recipe-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/07\/Tropical-Melon-Jello-Dessert-Recipe-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/07\/Tropical-Melon-Jello-Dessert-Recipe-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4247,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/ensalada-de-salmon-a-la-plancha-con-calabaza-butternut\/","url_meta":{"origin":2602,"position":3},"title":"Ensalada de Salm\u00f3n a la Plancha con Calabaza Butternut","author":"Chef Adriana Martin","date":"16 de septiembre de 2015","format":false,"excerpt":"Celebrando el oto\u00f1o con recetas sencillas","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"This Grilled Salmon Salad with Butternut Squash with a citrus dressing is the a wonderful option to offer the family","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/09\/This-Grilled-Salmon-Salad-with-Butternut-Squash-with-a-citrus-dressing-is-the-a-wonderful-option-to-offer-the-family-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/09\/This-Grilled-Salmon-Salad-with-Butternut-Squash-with-a-citrus-dressing-is-the-a-wonderful-option-to-offer-the-family-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/09\/This-Grilled-Salmon-Salad-with-Butternut-Squash-with-a-citrus-dressing-is-the-a-wonderful-option-to-offer-the-family-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4114,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/ensalada-de-tomatillos-con-mango\/","url_meta":{"origin":2602,"position":4},"title":"Ensalada de Tomatillos con Mango","author":"Chef Adriana Martin","date":"1 de agosto de 2015","format":false,"excerpt":"Una combinaci\u00f3n fresca y muy creativa","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/08\/Tomatillo-Salad-with-Mango-Vinaigrette-Recipe-at-Amigas-de-Comida-Kraft-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/08\/Tomatillo-Salad-with-Mango-Vinaigrette-Recipe-at-Amigas-de-Comida-Kraft-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/08\/Tomatillo-Salad-with-Mango-Vinaigrette-Recipe-at-Amigas-de-Comida-Kraft-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3385,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pollo-a-la-parrilla-estilo-italiano\/","url_meta":{"origin":2602,"position":5},"title":"Pollo a la Parrilla Estilo Italiano","author":"Chef Adriana Martin","date":"3 de febrero de 2015","format":false,"excerpt":"Pollo Estilo Italiano, una opci\u00f3n sin carbohidratos para comenzar el a\u00f1o","rel":"","context":"En \u00abDinner\u00bb","block_context":{"text":"Dinner","link":"https:\/\/www.adrianasbestrecipes.com\/category\/dinner\/"},"img":{"alt_text":"Grilled Italian Style Chicken Recipe for Amigas de Comida Kraft","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Grilled-Italian-Style-Chicken-Recipe-for-Amigas-de-Comida-Kraft-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Grilled-Italian-Style-Chicken-Recipe-for-Amigas-de-Comida-Kraft-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Grilled-Italian-Style-Chicken-Recipe-for-Amigas-de-Comida-Kraft-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/2602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/comments?post=2602"}],"version-history":[{"count":0,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/2602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media\/5815"}],"wp:attachment":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media?parent=2602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/categories?post=2602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/tags?post=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}