{"id":24946,"date":"2018-09-27T00:49:45","date_gmt":"2018-09-27T04:49:45","guid":{"rendered":"https:\/\/www.adrianasbestrecipes.com\/?p=24946"},"modified":"2018-09-27T01:59:13","modified_gmt":"2018-09-27T05:59:13","slug":"salsa-verde-de-pepitas-de-calabaza","status":"publish","type":"post","link":"https:\/\/www.adrianasbestrecipes.com\/es\/salsa-verde-de-pepitas-de-calabaza\/","title":{"rendered":"Salsa Verde de Pepitas de Calabaza"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Deliciosa salsa verde de pepitas de calabaza, una receta aut\u00e9ntica de M\u00e9xico<\/strong><\/p>\n<figure id=\"attachment_24961\" aria-describedby=\"caption-attachment-24961\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-24961\" title=\"Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg\" alt=\"Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza\" width=\"1000\" height=\"750\" data-pin-description=\"Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-24961\" class=\"wp-caption-text\">Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza<\/figcaption><\/figure>\n<p>Esta <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/salsa-verde-de-tomatillo-asado\/\" rel=\"noopener\">salsa verde<\/a> de pepitas es la que se usa para aderezar el pozole verde pero tambi\u00e9n es la base para el pepi\u00e1n, un platillo favorito del emperador Moctezuma antes de la conquista de los espa\u00f1oles. Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/sopa-de-flor-de-calabaza\/\" rel=\"noopener\">calabaza<\/a> tostadas, tomatillos, ajos, chiles serranos y cilantro. El secreto para obtener los sabores aut\u00e9nticos es tostar los ingredientes antes de licuar. Con el \u00fanico detalle que las pepitas no deben tostarse demasiado para que mantengan su color verde caracter\u00edstico.<\/p>\n<p style=\"text-align: center;\"><strong>Uso de las pepitas de calabaza<\/strong><\/p>\n<figure id=\"attachment_24963\" aria-describedby=\"caption-attachment-24963\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-24963\" title=\"Ingredientes para la salsa verde de pepitas \" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Ingredients-for-the-Green-Pepita-Sauce.jpg\" alt=\"Ingredientes para la salsa verde de pepitas \" width=\"1000\" height=\"750\" data-pin-description=\"Ingredientes para la salsa verde de pepitas \" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Ingredients-for-the-Green-Pepita-Sauce.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Ingredients-for-the-Green-Pepita-Sauce-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Ingredients-for-the-Green-Pepita-Sauce-500x375.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-24963\" class=\"wp-caption-text\">Ingredientes para la salsa verde de pepitas<\/figcaption><\/figure>\n<p>Muchas de las recetas tradicionales <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/malteadas-mexicanas\/\" rel=\"noopener\">mexicanas<\/a> tienen origen en nuestras ra\u00edces prehisp\u00e1nicas. En <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/puerco-pibil-estilo-yucatan\/\" rel=\"noopener\">Yucat\u00e1n<\/a> se utilizan mucho las pepitas para los papatzules y para hacer una salsa picante llamada H'a Sikil P'ak, hecha de habaneros ahumados, pepitas asadas, jugo de naranja agria y tomates asados.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/z9A6rf90iIQ?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>La salsa verde de pepitas de <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/calabaza-en-tacha-para-el-otono\/\" rel=\"noopener\">calabaza<\/a> es muy com\u00fan en la cocina del estado de Guerrero, lugar donde nace el delicioso pozole verde de cerdo. Cada regi\u00f3n de M\u00e9xico en tan rica en costumbres y sabores. Lo que hace que la cocina mexicana sea tan variada y exquisita.<\/p>\n<p>Esta salsa verde de pepitas se puede usar para aderezar no solo el pozole pero va muy bien con quesadillas, tacos, carne asada y dem\u00e1s. Pero tambi\u00e9n se puede usar para guisados como este <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/pepian-o-pipian-verde-con-pavo\/\" rel=\"noopener\">pepi\u00e1n de pavo<\/a>. Una opci\u00f3n maravillosa para el d\u00eda de acci\u00f3n de gracias o para cualquier cena especial.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a1Prepara la salsa verde de pepitas de calabaza es muy sencilla y deliciosa!<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-24965\" title=\"La salsa verde de pepitas de calabaza es originaria del Estado de Guerrero\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/The-green-pepita-sauce-is-a-typical-side-dish-from-Guerrero.jpg\" alt=\"La salsa verde de pepitas de calabaza es originaria del Estado de Guerrero\" width=\"1000\" height=\"1333\" data-pin-description=\"La salsa verde de pepitas de calabaza es originaria del Estado de Guerrero\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/The-green-pepita-sauce-is-a-typical-side-dish-from-Guerrero.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/The-green-pepita-sauce-is-a-typical-side-dish-from-Guerrero-225x300.jpg 225w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/The-green-pepita-sauce-is-a-typical-side-dish-from-Guerrero-768x1024.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-24973\" class=\"wprm-recipe-container\" data-recipe-id=\"24973\" data-servings=\"4\"><div class=\"wprm-recipe wprm-recipe-template-chic-with-instagram\"><div class=\"wprm-container-float-right\">\n    <div class=\"wprm-recipe-image wprm-block-image-rounded\"><img decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;border-radius: 3px;\" data-pin-nopin=\"true\" width=\"250\" height=\"250\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-400x400.jpg\" class=\"attachment-250x250 size-250x250\" alt=\"Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-400x400.jpg 400w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-180x180.jpg 180w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-500x500.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-45x45.jpg 45w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-125x125.jpg 125w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/div>\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\">Salsa Verde de Pepitas de Calabaza<\/h2>\n<div class=\"wprm-spacer\"><\/div>\n<span class=\"wprm-recipe-author-with-image\"><span class=\"wprm-recipe-author-image\"><img style=\"border-width: 0px;border-style: solid;border-color: #666666;border-radius: 50%;\" alt='' src='https:\/\/www.adrianasbestrecipes.com\/wp-content\/litespeed\/avatar\/0cc097d50acf463eb0bef6da38a4ac00.jpg?ver=1778178427' srcset='https:\/\/www.adrianasbestrecipes.com\/wp-content\/litespeed\/avatar\/18352e119a5c881e431dbe3c65b5e860.jpg?ver=1778178426 2x' class='avatar avatar-30 photo' height='30' width='30' \/><\/span><span class=\"wprm-recipe-details wprm-recipe-author wprm-block-text-light\">Chef Adriana Martin<\/span><\/span>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">Deliciosa salsa verde de pepitas de calabaza, una receta aut\u00e9ntica de M\u00e9xico. Hecha con semillas verdes de calabaza tostadas, tomatillos, ajo, chiles serranos y cilantro.<\/span><\/div>\n<div class=\"wprm-spacer\"><\/div>\n<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f5a623; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f5a623; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f5a623; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f5a623; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-24973 wprm-user-rating wprm-recipe-rating-inline wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"24973\" data-average=\"5\" data-count=\"1\" data-total=\"5\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-full\" data-rating=\"1\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 1 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-full\" data-rating=\"2\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 2 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-full\" data-rating=\"3\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 3 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-full\" data-rating=\"4\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 4 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-full\" data-rating=\"5\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 5 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\"><span class=\"wprm-recipe-rating-average\">5<\/span> from 1 vote<\/div><\/div>\n<div class=\"wprm-spacer\" style=\"height: 25px;\"><\/div>\n<div class=\"wprm-template-chic-buttons wprm-container-columns-spaced-middle wprm-container-columns-gutter\">\n\t<a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/wprm_print\/salsa-verde-de-pepitas-de-calabaza-2\" style=\"color: #ffffff;background-color: #f5a623;border-color: #f5a623;border-radius: 3px;padding: 10px 5px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-wide-button wprm-recipe-link-wide-button wprm-color-accent\" data-recipe-id=\"24973\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#ffffff\"><g><path d=\"M17.5454,0.0005 C18.2904,0.0005 18.9004,0.6105 18.9004,1.3565 L18.9004,1.3565 L18.9004,4.9445 L21.9904,4.9445 C23.0954,4.9445 24.0004,5.8485 24.0004,6.9535 L24.0004,6.9535 L24.0004,17.2415 C24.0004,18.3465 23.0954,19.2505 21.9904,19.2505 L21.9904,19.2505 L19.8414,19.2505 L19.8414,22.2795 C19.8414,23.1725 19.1104,23.9035 18.2174,23.9035 L18.2174,23.9035 L5.7834,23.9035 C4.8894,23.9035 4.1594,23.1725 4.1594,22.2795 L4.1594,22.2795 L4.1594,19.2505 L2.0104,19.2505 C0.9044,19.2505 0.0004,18.3465 0.0004,17.2415 L0.0004,17.2415 L0.0004,6.9535 C0.0004,5.8485 0.9044,4.9445 2.0104,4.9445 L2.0104,4.9445 L5.0984,4.9445 L5.0984,1.3565 C5.0984,0.6105 5.7094,0.0005 6.4554,0.0005 L6.4554,0.0005 Z M17.8414,15.5975 L6.1594,15.5975 L6.1594,21.9035 L17.8414,21.9035 L17.8414,15.5975 Z M21.9904,6.9445 L2.0104,6.9445 L2.0004,17.2415 L4.1594,17.2425 L4.1594,15.2215 C4.1594,14.3285 4.8894,13.5975 5.7834,13.5975 L5.7834,13.5975 L18.2174,13.5975 C19.1104,13.5975 19.8414,14.3285 19.8414,15.2215 L19.8414,15.2215 L19.8414,17.2495 L21.9904,17.2505 L22.0004,6.9535 L21.9904,6.9445 Z M6.1632,9.1318 C6.7902,9.1318 7.2992,9.6408 7.2992,10.2678 C7.2992,10.8948 6.7902,11.4028 6.1632,11.4028 L6.1632,11.4028 L5.0992,11.4028 C4.4722,11.4028 3.9632,10.8948 3.9632,10.2678 C3.9632,9.6408 4.4722,9.1318 5.0992,9.1318 L5.0992,9.1318 Z M16.6304,2.2715 L7.3704,2.2715 L7.3704,4.6845 L16.6304,4.6845 L16.6304,2.2715 Z\"><\/path><\/g><\/g><\/g><\/svg><\/span> Imprimir receta<\/a>\n\t\n    \n<\/div>\n<div class=\"wprm-spacer\" style=\"height: 20px;\"><\/div>\n<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><g><path d=\"M12,0 C18.627,0 24,4.373 24,11 C24,19.406 18.646,24 18.646,24 L18.646,24 L5.354,24 C5.354,24 0,19.406 0,11 C0,4.373 5.373,0 12,0 Z M12,2 C6.206,2 2,5.785 2,11 C2,16.956 4.962,20.716 6.168,22 L6.168,22 L17.832,22 C19.032,20.724 22,16.962 22,11 C22,5.785 17.794,2 12,2 Z M15.4175,17.7983 C15.9697847,17.7983 16.4175,18.2460153 16.4175,18.7983 C16.4175,19.3111358 16.0314598,19.7338072 15.5341211,19.7915723 L15.4175,19.7983 L8.5825,19.7983 C8.03021525,19.7983 7.5825,19.3505847 7.5825,18.7983 C7.5825,18.2854642 7.96854019,17.8627928 8.46587887,17.8050277 L8.5825,17.7983 L15.4175,17.7983 Z M12,4.2544 C15.173,4.2544 17.746,6.8264 17.746,10.0004 C17.746,13.1734 15.173,15.7454 12,15.7454 C8.827,15.7454 6.254,13.1734 6.254,10.0004 C6.254,6.8264 8.827,4.2544 12,4.2544 Z M10.9999773,6.38993761 C9.41864646,6.82850486 8.254,8.28073633 8.254,10.0004 C8.254,12.0654 9.935,13.7454 12,13.7454 C14.065,13.7454 15.746,12.0654 15.746,10.0004 C15.746,8.28110051 14.5818468,6.82911997 13.0010273,6.39021638 L13,9.2962 C13,9.84848475 12.5522847,10.2962 12,10.2962 C11.4871642,10.2962 11.0644928,9.91015981 11.0067277,9.41282113 L11,9.2962 Z\"><\/path><\/g><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Tiempo de preparaci\u00f3n <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">10<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-time-label wprm-recipe-cook-time-label\">Tiempo de cocci\u00f3n <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-cook_time wprm-recipe-cook_time-minutes\">5<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-time-container wprm-recipe-total-time-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-time-label wprm-recipe-total-time-label\">Tiempo Total <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-total_time wprm-recipe-total_time-minutes\">15<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-total_time-unit wprm-recipe-total_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><\/div>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-container-columns-spaced\">\n\t<div>\n    \t<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M19.5441,12.0586 L17.8411,12.3146 L17.8411,14.0376 L17.8411,17.8606 L6.1591,17.8606 L6.1591,14.0376 L6.1591,12.3146 L4.4561,12.0586 C3.0331,11.8446 2.0001,10.6536 2.0001,9.2246 C2.0001,7.6626 3.2471,6.3876 4.7971,6.3406 C4.8651,6.3486 4.9351,6.3556 5.0051,6.3576 L6.3221,6.4136 L6.8931,5.2246 C7.8481,3.2356 9.8051,1.9996 12.0001,1.9996 C14.1951,1.9996 16.1521,3.2356 17.1071,5.2246 L17.6781,6.4136 L18.9951,6.3576 C19.0641,6.3556 19.1321,6.3486 19.2021,6.3406 C20.7531,6.3866 22.0001,7.6626 22.0001,9.2246 C22.0001,10.6536 20.9671,11.8446 19.5441,12.0586 L19.5441,12.0586 Z M6.1591,22.0006 L17.8411,22.0006 L17.8411,19.8606 L6.1591,19.8606 L6.1591,22.0006 Z M19.1141,4.3386 C19.0451,4.3386 18.9801,4.3566 18.9101,4.3596 C17.6741,1.7836 15.0491,-0.0004 12.0001,-0.0004 C8.9511,-0.0004 6.3261,1.7836 5.0901,4.3596 C5.0211,4.3566 4.9551,4.3386 4.8861,4.3386 C2.1881,4.3386 0.0001,6.5266 0.0001,9.2246 C0.0001,11.6736 1.8081,13.6836 4.1591,14.0376 L4.1591,22.3756 C4.1591,23.2696 4.8901,23.9996 5.7831,23.9996 L18.2171,23.9996 C19.1101,23.9996 19.8411,23.2696 19.8411,22.3756 L19.8411,14.0376 C22.1911,13.6836 24.0001,11.6736 24.0001,9.2246 C24.0001,6.5266 21.8131,4.3386 19.1141,4.3386 L19.1141,4.3386 Z\" id=\"Fill-1\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-course-label\">Plato <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Guarnici\u00f3n y Acompa\u00f1amientos, Salsas<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cocina <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">Cocina Mexicana<\/span><\/div><\/div>\n    <\/div>\n    <div>\n        <div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M15.9199,4.9443 L18.1399,2.7243 C18.5509,2.3133 19.0909,2.1083 19.6299,2.1083 C20.1699,2.1083 20.7099,2.3133 21.1209,2.7243 C21.9429,3.5473 21.9419,4.8843 21.1209,5.7073 L18.9019,7.9253 C18.0799,8.7483 16.7419,8.7483 15.9199,7.9253 C15.0979,7.1033 15.0979,5.7663 15.9199,4.9443 M23.5529,22.1383 L13.3369,11.9233 L15.3109,9.9493 C15.9559,10.3353 16.6809,10.5413 17.4109,10.5413 C18.4629,10.5413 19.5159,10.1403 20.3159,9.3403 L22.5349,7.1213 C24.1369,5.5183 24.1369,2.9123 22.5349,1.3103 C21.7599,0.5343 20.7279,0.1073 19.6299,0.1073 C18.5329,0.1073 17.5019,0.5343 16.7259,1.3103 L14.5059,3.5303 C13.7299,4.3063 13.3029,5.3383 13.3029,6.4343 C13.3029,7.1883 13.5179,7.9053 13.8959,8.5363 L11.9229,10.5083 L9.9489,8.5353 C10.8909,6.9593 10.6959,4.8863 9.3399,3.5303 L6.1039,0.2933 C5.7129,-0.0977 5.0799,-0.0977 4.6899,0.2933 C4.2989,0.6833 4.2989,1.3163 4.6899,1.7073 L7.9259,4.9443 C8.4909,5.5093 8.6579,6.3153 8.4459,7.0323 L3.6539,2.2403 C3.2639,1.8493 2.6309,1.8493 2.2399,2.2403 C1.8499,2.6313 1.8499,3.2633 2.2399,3.6543 L7.0319,8.4463 C6.3149,8.6583 5.5089,8.4913 4.9429,7.9253 L1.7069,4.6893 C1.3159,4.2983 0.6839,4.2983 0.2929,4.6893 C-0.0981,5.0803 -0.0981,5.7133 0.2929,6.1033 L3.5289,9.3403 C4.3309,10.1403 5.3829,10.5413 6.4349,10.5413 C7.1649,10.5413 7.8899,10.3353 8.5349,9.9493 L10.5089,11.9233 L0.2929,22.1383 C-0.0981,22.5293 -0.0981,23.1623 0.2929,23.5523 C0.4879,23.7483 0.7439,23.8453 0.9999,23.8453 C1.2559,23.8453 1.5119,23.7483 1.7069,23.5523 L11.9229,13.3373 L22.1389,23.5523 C22.3339,23.7483 22.5899,23.8453 22.8459,23.8453 C23.1019,23.8453 23.3569,23.7483 23.5529,23.5523 C23.9429,23.1623 23.9429,22.5293 23.5529,22.1383\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-servings-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-servings-label\">Raciones <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-24973 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"24973\" aria-label=\"Adjust recipe servings\">4<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">tazas<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-nutrition-container wprm-recipe-calories-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-nutrition-label wprm-recipe-calories-label\">Calor\u00edas <\/span><span class=\"wprm-recipe-details wprm-recipe-nutrition wprm-recipe-calories wprm-block-text-normal\"><\/span><\/div><\/div>\n    <\/div>\n<\/div>\n\n<div id=\"recipe-24973-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-24973-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"24973\" data-servings=\"4\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line wprm-header-has-actions wprm-header-has-actions\" style=\"\">Ingredientes<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div>&nbsp;&nbsp;<div class=\"wprm-recipe-adjustable-servings-container wprm-recipe-adjustable-servings-24973-container wprm-toggle-container wprm-toggle-buttons-container wprm-block-text-normal\" style=\"--wprm-toggle-button-accent: #616161;\"><button class=\"wprm-recipe-adjustable-servings wprm-toggle wprm-toggle-active\" data-multiplier=\"1\" data-servings=\"4\" data-recipe=\"24973\" aria-label=\"Adjust servings by 1x\">1x<\/button><button class=\"wprm-recipe-adjustable-servings wprm-toggle\" data-multiplier=\"2\" data-servings=\"4\" data-recipe=\"24973\" aria-label=\"Adjust servings by 2x\">2x<\/button><button class=\"wprm-recipe-adjustable-servings wprm-toggle\" data-multiplier=\"3\" data-servings=\"4\" data-recipe=\"24973\" aria-label=\"Adjust servings by 3x\">3x<\/button><\/div><\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de pepitas asadas<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">10<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">tomatillos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">3<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">dientes de ajo<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">8<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">chiles serranos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">manojo de cilantro<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1\/3<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de agua<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharadita <\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de comino<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharadita<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de sal marina granulada<\/span><\/li><\/ul><\/div><\/div>\n<div id=\"recipe-24973-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-24973-instructions-container wprm-block-text-normal\" data-recipe=\"24973\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line wprm-header-has-actions\" style=\"\">Instrucciones<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div>&nbsp;<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-24973-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Limpia los tomatillos removiendo la c\u00e1scara. Usa agua corriente para lavarlos junto con los chiles serranos. Pela los dientes de ajo. Cortar un peque\u00f1o manojo de cilantro y limpia bajo el chorro de agua. D\u00e9jalo reposar sobre una toalla para que se seque.<\/span><\/div><\/li><li id=\"wprm-recipe-24973-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">En una sart\u00e9n asa las pepitas verdes ligeramente. Aseg\u00farate de no quemarlas. Las semillas de calabaza se tuestan para liberar los aceites y he incrementar su sabor anuezado.&nbsp;<\/span><\/div><\/li><li id=\"wprm-recipe-24973-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">En un comal o en una sart\u00e9n, tuesta los tomatillos, los serranos y el ajo. Aseg\u00farate de tostar bien, ya que este proceso de asado es lo que le da el aut\u00e9ntico sabor mexicano a la salsa.<\/span><\/div><\/li><li id=\"wprm-recipe-24973-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Coloca todos los ingredientes en la licuadora, agrega un poco de agua, sal marina granulada y comino.<\/span><\/div><\/li><li id=\"wprm-recipe-24973-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Lic\u00faa hasta obtener una salsa espesa y empaca en un tarro de cristal o en un recipiente de pl\u00e1stico con tapa. Manten la salsa refrigerada o bien en el congelador.<\/span><\/div><\/li><\/ul><\/div><\/div>\n<div id=\"recipe-video\"><\/div><div id=\"wprm-recipe-video-container-24973\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">V\u00eddeo<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-recipe-video\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/z9A6rf90iIQ\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/div><\/div>\n<div id=\"recipe-24973-notes\" class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">Notas<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-recipe-notes\"><ul>\n<li>El secreto para obtener los sabores aut\u00e9nticos de esta salsa es tostar los ingredientes antes de licuar.<\/li>\n<li>Las pepitas no deben tostarse demasiado para mantener su caracter\u00edstico color verde.<\/li>\n<\/ul><\/div><\/div>\n<div id=\"recipe-24973-nutrition\" class=\"wprm-nutrition-label-shortcode-container\"><h3 class=\"wprm-recipe-header wprm-recipe-nutrition-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">Nutrici\u00f3n<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-nutrition-label-container wprm-nutrition-label-container-grouped wprm-block-text-normal wprm-nutrition-label-container-grouped-text\" style=\"text-align: left;column-gap: 10px;\"><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-serving_size\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Raci\u00f3n: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-carbohydrates\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Carbohidratos: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-protein\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Proteina: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-saturated_fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa saturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-polyunsaturated_fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa polinsaturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-monounsaturated_fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa monosaturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-trans_fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa Transg\u00e9nica: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-cholesterol\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Colesterol: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sodium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Sodio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-potassium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Potasio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fiber\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Fibra: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sugar\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Az\u00facar: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_a\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Vitamina A: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">IU<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_c\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Vitamina C: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-calcium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Calcio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-iron\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Hierro: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">0<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-empty\" style=\"flex-basis: 175px\"><\/span><\/div><\/div>\n<div class=\"wprm-spacer\" style=\"height: 20px;\"><\/div>\n<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g id=\"Icons\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M9.0039,16.0079 C5.1419,16.0079 1.9999,12.8659 1.9999,9.0039 C1.9999,5.1419 5.1419,1.9999 9.0039,1.9999 C12.8659,1.9999 16.0079,5.1419 16.0079,9.0039 C16.0079,12.8659 12.8659,16.0079 9.0039,16.0079 M23.6209,22.2069 L16.1439,14.7299 C16.1059,14.6919 16.0579,14.6759 16.0159,14.6449 C17.2599,13.1009 18.0079,11.1409 18.0079,9.0039 C18.0079,4.0309 13.9769,-0.0001 9.0039,-0.0001 C4.0309,-0.0001 -0.0001,4.0309 -0.0001,9.0039 C-0.0001,13.9769 4.0309,18.0079 9.0039,18.0079 C11.1409,18.0079 13.1009,17.2599 14.6449,16.0169 C14.6749,16.0579 14.6919,16.1059 14.7299,16.1439 L22.2069,23.6209 C22.4019,23.8169 22.6579,23.9139 22.9139,23.9139 C23.1699,23.9139 23.4259,23.8169 23.6209,23.6209 C24.0119,23.2309 24.0119,22.5979 23.6209,22.2069\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Palabra clave <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">pepitas, salsa verde, tomatillos<\/span><\/div><\/div>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-call-to-action wprm-call-to-action-simple\" style=\"color: #ffffff;background-color: #f5a623;margin: 0px;padding-top: 30px;padding-bottom: 30px;\"><span class=\"wprm-recipe-icon wprm-call-to-action-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#ffffff\"><path fill=\"#ffffff\" d=\"M12,2.162c3.204,0,3.584,0.012,4.849,0.07c1.366,0.062,2.633,0.336,3.608,1.311 c0.975,0.975,1.249,2.242,1.311,3.608c0.058,1.265,0.07,1.645,0.07,4.849s-0.012,3.584-0.07,4.849 c-0.062,1.366-0.336,2.633-1.311,3.608c-0.975,0.975-2.242,1.249-3.608,1.311c-1.265,0.058-1.645,0.07-4.849,0.07 s-3.584-0.012-4.849-0.07c-1.366-0.062-2.633-0.336-3.608-1.311c-0.975-0.975-1.249-2.242-1.311-3.608 c-0.058-1.265-0.07-1.645-0.07-4.849s0.012-3.584,0.07-4.849c0.062-1.366,0.336-2.633,1.311-3.608 c0.975-0.975,2.242-1.249,3.608-1.311C8.416,2.174,8.796,2.162,12,2.162 M12,0C8.741,0,8.332,0.014,7.052,0.072 c-1.95,0.089-3.663,0.567-5.038,1.942C0.639,3.389,0.161,5.102,0.072,7.052C0.014,8.332,0,8.741,0,12 c0,3.259,0.014,3.668,0.072,4.948c0.089,1.95,0.567,3.663,1.942,5.038c1.375,1.375,3.088,1.853,5.038,1.942 C8.332,23.986,8.741,24,12,24s3.668-0.014,4.948-0.072c1.95-0.089,3.663-0.567,5.038-1.942c1.375-1.375,1.853-3.088,1.942-5.038 C23.986,15.668,24,15.259,24,12s-0.014-3.668-0.072-4.948c-0.089-1.95-0.567-3.663-1.942-5.038 c-1.375-1.375-3.088-1.853-5.038-1.942C15.668,0.014,15.259,0,12,0L12,0z\"><\/path> <path data-color=\"color-2\" d=\"M12,5.838c-3.403,0-6.162,2.759-6.162,6.162S8.597,18.162,12,18.162s6.162-2.759,6.162-6.162 S15.403,5.838,12,5.838z M12,16c-2.209,0-4-1.791-4-4s1.791-4,4-4s4,1.791,4,4S14.209,16,12,16z\"><\/path> <circle data-color=\"color-2\" cx=\"18.406\" cy=\"5.594\" r=\"1.44\"><\/circle><\/g><\/svg><\/span> <span class=\"wprm-call-to-action-text-container\"><span class=\"wprm-call-to-action-header\" style=\"color: #ffffff;\">\u00bfHas probado esta receta?<\/span><span class=\"wprm-call-to-action-text\">Mention <a href=\"https:\/\/www.instagram.com\/adrianasbestrecipes\" target=\"_blank\" rel=\"noreferrer noopener\" style=\"color: #ffffff\">@adrianasbestrecipes<\/a> or tag <a href=\"https:\/\/www.instagram.com\/explore\/tags\/abrecipes\" target=\"_blank\" rel=\"noreferrer noopener\" style=\"color: #ffffff\">#abrecipes<\/a> on Instagram<\/span><\/span><\/div><\/div><\/div>\n<div>\n<h2 class=\"tbf-aapr-header\">Products from Amazon.com<\/h2>\n<\/div>\n<p><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B00IC8S8YW\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B01BLYNWVM\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B000JLYQIC\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B0029JU8SE\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B00KPX1C9U\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B0753GZYYY\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B075713NNL\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B07CX95VRT\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><script type=\"text\/javascript\">\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"manual\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_design = \"enhanced_links\";\namzn_assoc_asins = \"B00K8NKWMK\";\namzn_assoc_placement = \"adunit\";\n<\/script><script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa!<\/p>\n","protected":false},"author":2,"featured_media":24961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Salsa Verde de Pepitas","_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[628,73,3474,513],"tags":[],"class_list":["post-24946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-facil-y-rapido","category-guarniciones-snacks","category-videos","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_featured_media_url":"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg","spectra_custom_meta":{"_edit_lock":["1538027865:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_content_score":["60"],"swp_pin_browser_extension":["default"],"swp_pin_browser_extension_location":["default"],"swp_post_location":["default"],"swp_float_location":["default"],"true":["true"],"_genesis_scripts_body_position":["bottom"],"_yoast_wpseo_primary_category":["73"],"_yoast_wpseo_focuskw":["Salsa Verde de Pepitas"],"_yoast_wpseo_linkdex":["94"],"_yoast_wpseo_metadesc":["Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro."],"swp_custom_tweet":["Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa #CocinaMexicana #RecetasDeliciosas"],"swp_pinterest_description":["Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro. El secreto para obtener los sabores aut\u00e9nticos es tostar los ingredientes antes de licuar. Con el \u00fanico detalle que las pepitas no deben tostarse demasiado para que mantengan su color verde caracter\u00edstico.\u00a0#CocinaMexicana #RecetasDeliciosas"],"_thumbnail_id":["24961"],"wprm_rating":["a:4:{s:5:\"count\";i:1;s:5:\"total\";i:5;s:7:\"average\";d:5;s:4:\"type\";a:3:{s:7:\"comment\";i:0;s:10:\"no_comment\";i:0;s:4:\"user\";i:1;}}"],"wprm_rating_average":["5"],"swp_pinterest_image":["24979"],"_google_plus_shares":["0"],"bitly_link_google_plus":["http:\/\/bit.ly\/2N3Ty7O"],"swp_open_graph_image_data":["false"],"swp_open_graph_image_url":[""],"_facebook_shares":["0"],"_pinterest_shares":["2"],"_buffer_shares":["0"],"_yummly_shares":["0"],"_twitter_shares":["0"],"_whatsapp_shares":["0"],"_flipboard_shares":["0"],"_mix_shares":["0"],"_email_shares":["0"],"_total_shares":["2"],"swp_pinterest_image_data":["[\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Esta-receta-para-la-salsa-verde-de-pepitas-estau0301-hecha-con-pepitas-de-calabaza-tostadas.jpg\",750,1125,false]"],"swp_pinterest_image_url":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Esta-receta-para-la-salsa-verde-de-pepitas-esta\u0301-hecha-con-pepitas-de-calabaza-tostadas.jpg"],"bitly_link_facebook":["http:\/\/bit.ly\/2u4baJm"],"bitly_link_twitter":["http:\/\/bit.ly\/2u18e0d"],"bitly_link_mix":["http:\/\/bit.ly\/2u2B1BH"],"bitly_link_buffer":["http:\/\/bit.ly\/2u2B2Wh"],"bitly_link_flipboard":["http:\/\/bit.ly\/2u2B4gR"],"bitly_link_email":["http:\/\/bit.ly\/2u1ngmM"],"bitly_link_whatsapp":["http:\/\/bit.ly\/2u2B68t"],"bitly_link_yummly":["http:\/\/bit.ly\/2u2AShD"],"swp_cache_timestamp":["431302"],"dpsp_share_options":["a:3:{s:12:\"custom_tweet\";s:104:\"Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa #CocinaMexicana #RecetasDeliciosas\";s:28:\"custom_description_pinterest\";s:379:\"Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro. El secreto para obtener los sabores aut\u00e9nticos es tostar los ingredientes antes de licuar. Con el \u00fanico detalle que las pepitas no deben tostarse demasiado para que mantengan su color verde caracter\u00edstico.\u00a0#CocinaMexicana #RecetasDeliciosas\";s:22:\"custom_image_pinterest\";a:2:{s:2:\"id\";s:5:\"24979\";s:3:\"src\";s:155:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Esta-receta-para-la-salsa-verde-de-pepitas-esta\u0301-hecha-con-pepitas-de-calabaza-tostadas.jpg\";}}"],"dpsp_networks_shares":["a:7:{s:9:\"pinterest\";i:14;s:8:\"facebook\";i:5;s:7:\"twitter\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;s:4:\"grow\";i:4;}"],"dpsp_networks_shares_total":["23"],"dpsp_networks_shares_last_updated":["1643382437"],"dpsp_cache_shares_twitter_2":["0"],"dpsp_short_link_bitly":["a:14:{s:18:\"facebook_short_url\";s:21:\"http:\/\/bit.ly\/2G7sPXq\";s:17:\"twitter_short_url\";s:21:\"http:\/\/bit.ly\/2G8weFD\";s:18:\"whatsapp_short_url\";s:21:\"http:\/\/bit.ly\/2G6POlx\";s:16:\"yummly_short_url\";s:21:\"http:\/\/bit.ly\/2G7UAPT\";s:15:\"email_short_url\";s:21:\"http:\/\/bit.ly\/2GaC6OR\";s:13:\"mix_short_url\";s:21:\"http:\/\/bit.ly\/31fxyxB\";s:19:\"flipboard_short_url\";s:21:\"http:\/\/bit.ly\/2MfU0CG\";s:18:\"linkedin_short_url\";s:21:\"http:\/\/bit.ly\/31iNjEa\";s:16:\"reddit_short_url\";s:21:\"http:\/\/bit.ly\/2MJ5b5P\";s:16:\"buffer_short_url\";s:21:\"http:\/\/bit.ly\/2IRAJoQ\";s:18:\"telegram_short_url\";s:21:\"http:\/\/bit.ly\/2VL4ddt\";s:14:\"grow_short_url\";s:22:\"https:\/\/bit.ly\/3vLHuyF\";s:17:\"threads_short_url\";s:22:\"https:\/\/bit.ly\/3KLKWTA\";s:18:\"mastodon_short_url\";s:22:\"https:\/\/bit.ly\/3Vz05MZ\";}"],"_jetpack_related_posts_cache":["a:1:{s:32:\"8f6677c9d6b0f903e98ad32ec61f8deb\";a:2:{s:7:\"expires\";i:1622285780;s:7:\"payload\";a:3:{i:0;a:1:{s:2:\"id\";i:9639;}i:1;a:1:{s:2:\"id\";i:2958;}i:2;a:1:{s:2:\"id\";i:17616;}}}}"],"dpsp_post_previous_urls":["a:1:{i:0;s:85:\"https:\/\/www.adrianasbestrecipes.com\/es\/2018\/09\/27\/salsa-verde-de-pepitas-de-calabaza\/\";}"],"dpsp_networks_shares_previous_urls":["a:5:{s:8:\"facebook\";i:1;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:2;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;}"],"_tbf_fix_details":["a:5:{s:6:\"fix_id\";s:4:\"5097\";s:19:\"changed_revision_id\";s:5:\"24946\";s:20:\"original_revision_id\";s:5:\"24946\";s:17:\"operation_set_ids\";s:36:\"images_performance_and_seo_optimizer\";s:10:\"operations\";a:1:{i:0;s:11:\"tag_replace\";}}"],"_yoast_wpseo_video_meta":["a:16:{s:2:\"id\";s:11:\"z9A6rf90iIQ\";s:3:\"url\";s:28:\"https:\/\/youtu.be\/z9A6rf90iIQ\";s:4:\"type\";s:7:\"youtube\";s:10:\"player_loc\";s:41:\"https:\/\/www.youtube.com\/embed\/z9A6rf90iIQ\";s:13:\"thumbnail_loc\";s:78:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/z9a6rf90iiq.jpg\";s:12:\"last_fetched\";i:1678079257;s:8:\"duration\";i:98;s:10:\"view_count\";s:4:\"1846\";s:5:\"width\";i:480;s:6:\"height\";i:270;s:7:\"post_id\";i:24946;s:5:\"title\";s:68:\"Salsa Verde de Pepitas de Calabaza - Adriana&amp;#039;s Best Recipes\";s:16:\"publication_date\";s:25:\"2018-09-27T04:49:45+00:00\";s:11:\"description\";s:134:\"Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro.\";s:8:\"category\";s:7:\"Cultura\";s:3:\"tag\";a:1:{i:0;s:22:\"Salsa Verde de Pepitas\";}}"],"litespeed_vpi_list":["a:3:{i:0;s:37:\"ABRecipes-New-Logo-with-Trademark.jpg\";i:1;s:32:\"Authentic-green-pepita-sauce.jpg\";i:2;s:36:\"Adriana-Martin-TACOS-23-683x1024.jpg\";}"],"_seopress_titles_desc":["Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro."],"_seopress_analysis_target_kw":["Salsa Verde de Pepitas"],"dpsp_share_options_json":["{\"custom_tweet\":\"Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa #CocinaMexicana #RecetasDeliciosas\",\"custom_description_pinterest\":\"Esta receta para la salsa verde de pepitas est\u00e1 hecha con pepitas de calabaza tostadas, tomatillos, ajos, chiles serranos y cilantro. El secreto para obtener los sabores aut\u00e9nticos es tostar los ingredientes antes de licuar. Con el \u00fanico detalle que las pepitas no deben tostarse demasiado para que mantengan su color verde caracter\u00edstico.\u00a0#CocinaMexicana #RecetasDeliciosas\",\"custom_image_pinterest\":{\"id\":\"24979\",\"src\":\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Esta-receta-para-la-salsa-verde-de-pepitas-esta\u0301-hecha-con-pepitas-de-calabaza-tostadas.jpg\"}}"],"dpsp_networks_shares_json":["{\"pinterest\":14,\"facebook\":5,\"twitter\":0,\"yummly\":0,\"reddit\":0,\"buffer\":0,\"grow\":4}"],"wprm_rating_no_text_comments":["a:0:{}"],"wprm_rating_count":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:0:{}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778691283\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",1000,750,false],"thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-180x180.jpg",180,180,true],"medium":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",1000,750,false],"large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",1000,750,false],"1536x1536":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",1000,750,false],"2048x2048":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",1000,750,false],"wprm-metadata-1_1":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-500x500.jpg",500,500,true],"wprm-metadata-4_3":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-480x270.jpg",480,270,true],"rpwe-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-45x45.jpg",45,45,true],"mailchimp":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce-560x420.jpg",560,420,true],"web-stories-poster-portrait":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg",150,113,false]},"uagb_author_info":{"display_name":"Chef Adriana Martin","author_link":"https:\/\/www.adrianasbestrecipes.com\/es\/author\/adriana\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a1Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa!","jetpack-related-posts":[{"id":9639,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pasta-otonal\/","url_meta":{"origin":24946,"position":0},"title":"Pasta Oto\u00f1al para el Men\u00fa de Thanksgiving","author":"Chef Adriana Martin","date":"11 de noviembre de 2016","format":false,"excerpt":"Receta f\u00e1cil para hacer pasta oto\u00f1al hecha con salsa marinara de ajo tostado, calabaza, chipotle, pepitas y queso fresco. Una deliciosa adici\u00f3n para el men\u00fa de Acci\u00f3n de Gracias.","rel":"","context":"En \u00abAlmuerzo\u00bb","block_context":{"text":"Almuerzo","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/almuerzo-es\/"},"img":{"alt_text":"Fall pasta for Thanksgiving has butternut squash, chipotle, pepitas and tomato sauce.","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17616,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pepian-o-pipian-verde-con-pavo\/","url_meta":{"origin":24946,"position":1},"title":"Pepian o Pipian Verde con Pavo","author":"Chef Adriana Martin","date":"9 de noviembre de 2017","format":false,"excerpt":"El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote.","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"Pepian o Pipian Verde con Pavo","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24160,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pozole-verde-de-cerdo-instant-pot\/","url_meta":{"origin":24946,"position":2},"title":"Pozole Verde de Cerdo Instant Pot","author":"Chef Adriana Martin","date":"27 de septiembre de 2018","format":false,"excerpt":"Inspirada en la receta cl\u00e1sica del Pozole Verde, cocin\u00e9 una versi\u00f3n actualizada del Pozole Verde de Cerdo utilizando el Instant Pot en lugar de una olla a presi\u00f3n com\u00fan.","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"Pozole Verde de Cerdo cocinado en el Instant Pot","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":282,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/crema-de-calabaza\/","url_meta":{"origin":24946,"position":3},"title":"Crema de Calabaza","author":"Chef Adriana Martin","date":"1 de octubre de 2012","format":false,"excerpt":"\u00a1Disfruta esta exquisita sopa con tu familia!","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"Pumpkin soup","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2011\/10\/Pumpkin-soup.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2011\/10\/Pumpkin-soup.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2011\/10\/Pumpkin-soup.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2011\/10\/Pumpkin-soup.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3199,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/crema-de-calabaza-bellota-ninjakitchen-ad\/","url_meta":{"origin":24946,"position":4},"title":"Crema de Calabaza Bellota","author":"Chef Adriana Martin","date":"6 de diciembre de 2014","format":false,"excerpt":"Deliciosa Crema de Calabaza Bellota con Leche de Coco para el Invierno","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"Coconut Acorn Squash Soup Recipe","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/12\/Coconut-Acorn-Squash-Soup-Recipe-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/12\/Coconut-Acorn-Squash-Soup-Recipe-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2014\/12\/Coconut-Acorn-Squash-Soup-Recipe-1-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3493,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/calabaza-espagueti-en-salsa-marinara\/","url_meta":{"origin":24946,"position":5},"title":"Calabaza Espagueti en Salsa Marinara","author":"Chef Adriana Martin","date":"27 de febrero de 2015","format":false,"excerpt":"Calabaza Espagueti en Salsa Marinara, un platillo muy sabroso para la Cuaresma","rel":"","context":"En \u00abAlmuerzo\u00bb","block_context":{"text":"Almuerzo","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/almuerzo-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/02\/Marinara-Spaguetti-squash-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/24946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/comments?post=24946"}],"version-history":[{"count":0,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/24946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media\/24961"}],"wp:attachment":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media?parent=24946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/categories?post=24946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/tags?post=24946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}