{"id":17616,"date":"2017-11-09T00:59:24","date_gmt":"2017-11-09T05:59:24","guid":{"rendered":"https:\/\/www.adrianasbestrecipes.com\/?post_type=recipe&#038;p=17616"},"modified":"2020-11-22T02:30:18","modified_gmt":"2020-11-22T07:30:18","slug":"pepian-o-pipian-verde-con-pavo","status":"publish","type":"post","link":"https:\/\/www.adrianasbestrecipes.com\/es\/pepian-o-pipian-verde-con-pavo\/","title":{"rendered":"Pepian o Pipian Verde con Pavo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.adrianasbestrecipes.com\/recipe\/green-pepian-turkey-dinner\/green-pepian-turkey-dinner-2\/\" rel=\"attachment wp-att-17634\"><img decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg\" alt=\"Pepian o Pipian Verde con Pavo\" class=\"wp-image-17634\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-560x420.jpg 560w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-600x450.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong> Pepian o Pipian Verde con Pavo, Exquisito Platillo Cl\u00e1sico Mexicano cocinado con la t\u00e9cnica Sous Vide<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pepian o pipi\u00e1n tambi\u00e9n es llamado <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/chilaquiles-de-mole-para-el-desayuno\/\">mole<\/a> verde y es una salsa muy especial. Hecha con <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/pepitas-y-loteria\/\">pepitas<\/a> de calabaza y condimentos especiales como el epazote y las semillas de comino. Adem\u00e1s de chiles serranos asados, tomatillos y ajo. Todo mezclado para hacer la salsa m\u00e1s muy sabrosa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pepian verde va muy bien con la carne de pavo, el pollo o bien con carne de <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/costillitas-de-cerdo\/\">cerdo<\/a>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.adrianasbestrecipes.com\/recipe\/green-pepian-turkey-dinner\/green-pepian-or-also-called-mole-verde-a-classic-mexican-dish\/\" rel=\"attachment wp-att-17642\"><img decoding=\"async\" width=\"1000\" height=\"1334\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish.jpg\" alt=\"Pepi\u00e1n Verde tambi\u00e9n conocido como mole verde. Un platillo cl\u00e1sico de la cocina mexicana\" class=\"wp-image-17642\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish-225x300.jpg 225w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish-768x1024.jpg 768w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish-150x200.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish-600x800.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-also-called-mole-verde-a-classic-Mexican-dish-560x747.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>El Pepian Verde tambi\u00e9n conocido como mole verde. Un platillo cl\u00e1sico de la cocina mexicana.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta vez estoy sirviendo el pepian verde con pavo cocinado en el sous vide para lograr una carne de pavo jugosa y suave que incluso se puede cortar con un tenedor. Una verdadera delicia que se derrite en la boca. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cocinamos el pepian verde con pavo usando la t\u00e9cnica sous vide es una buena idea cuando se trabaja con carnes que tienden a secarse en la cocci\u00f3n o que son de consistencia dura. Al sellar la carne al vac\u00edo incrementa el sabor resultando en una carne bien sazonada y de consistencia suave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos chefs usan esta t\u00e9cnica del sous vide para servir comidas perfectas como este delicioso pipian. Y a pesar de que es una herramienta muy com\u00fan en las cocinas profesionales, todos podemos usar el sous vide en casa. Es tan f\u00e1cil como usar una olla de cocci\u00f3n lenta, pero eleva la calidad y el sabor especialmente de las carnes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer el pepian o mole verde es muy simple, solo necesitas seguir las instrucciones en el video y \/ o la tarjeta de la receta. Este mole verde es perfecto para reinventar las sobras de pavo despu\u00e9s del d\u00eda de <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/pasta-otonal\/\">Acci\u00f3n de Gracias<\/a>\u00a0o la Navidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cocina mexicana tiene una influencia importante de la cultura culinaria prehisp\u00e1nica. Es com\u00fan ver condimentos como el epazote en muchas recetas cl\u00e1sicas. El epazote es una hoja conocida como t\u00e9 de los jesuitas o t\u00e9 mexicano. Es una hierba anual nativa de Am\u00e9rica Central, Am\u00e9rica del Sur y el sur de M\u00e9xico. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.adrianasbestrecipes.com\/recipe\/green-pepian-turkey-dinner\/cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection\/\" rel=\"attachment wp-att-17641\"><img decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection.jpg\" alt=\"Cocinamos el pavo en sous vide para lograr la perfecci\u00f3n\" class=\"wp-image-17641\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection-600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Cooking-the-turkey-tenderloin-on-the-sous-vide-to-achieve-perfection-560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"> <strong>Cocinamos el pavo en pipian en sous vide para lograr la perfecci\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crec\u00ed viendo viendo como mi mam\u00e1 cortaba el epazote de nuestro propio <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/sembrando-un-jardin-para-gatos\/\">jard\u00edn<\/a>. Esta hierba es un ingrediente muy com\u00fan y es usado en antojitos como las quesadillas de <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/tortitas-de-platano-goautentico-ad\/\">queso fresco<\/a> o quesillo y en los <a rel=\"noopener\" href=\"https:\/\/www.adrianasbestrecipes.com\/es\/frijoles-negros-cubanos\/\">frijoles negros<\/a>, as\u00ed como se agrega al reques\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He tratado de plantar epazote aqu\u00ed en la Florida, pero parece que a esta hierba le gusta el clima m\u00e1s fr\u00edo, as\u00ed que no he tenido \u00e9xito. Pero compro el epazote seco en tiendas especializadas y en Amazon. Muchos condimentos e ingredientes que son dif\u00edciles de encontrar Amazon los vende.<\/p>\n\n\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-23298\" class=\"wprm-recipe-container\" data-recipe-id=\"23298\" data-servings=\"6\"><div class=\"wprm-recipe wprm-recipe-template-chic-with-instagram\"><div class=\"wprm-container-float-right\">\n    <div class=\"wprm-recipe-image wprm-block-image-rounded\"><img decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;border-radius: 3px;\" data-pin-nopin=\"true\" width=\"250\" height=\"250\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-400x400.jpg\" class=\"attachment-250x250 size-250x250\" alt=\"Pepian o Pipian Verde con Pavo\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-400x400.jpg 400w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-180x180.jpg 180w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-500x500.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-45x45.jpg 45w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-125x125.jpg 125w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/div>\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\">Pepi\u00e1n o Pipi\u00e1n Verde con Pavo<\/h2>\n<div class=\"wprm-spacer\"><\/div>\n<span class=\"wprm-recipe-author-with-image\"><span class=\"wprm-recipe-author-image\"><img style=\"border-width: 0px;border-style: solid;border-color: #666666;border-radius: 50%;\" alt='' src='https:\/\/www.adrianasbestrecipes.com\/wp-content\/litespeed\/avatar\/0cc097d50acf463eb0bef6da38a4ac00.jpg?ver=1783621989' srcset='https:\/\/www.adrianasbestrecipes.com\/wp-content\/litespeed\/avatar\/18352e119a5c881e431dbe3c65b5e860.jpg?ver=1783621988 2x' class='avatar avatar-30 photo' height='30' width='30' \/><\/span><span class=\"wprm-recipe-details wprm-recipe-author wprm-block-text-light\">Chef Adriana Martin<\/span><\/span>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote. El pepian va muy bien con aves o con carne de puerco.<\/div>\n<div class=\"wprm-spacer\"><\/div>\n<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f5a623; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f5a623; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f5a623; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f5a623; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-23298 wprm-user-rating wprm-recipe-rating-inline wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"23298\" data-average=\"0\" data-count=\"0\" data-total=\"0\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-empty\" data-rating=\"1\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 1 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-empty\" data-rating=\"2\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 2 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-empty\" data-rating=\"3\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 3 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-empty\" data-rating=\"4\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 4 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-empty\" data-rating=\"5\" data-color=\"#f5a623\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 5 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g  transform=\"translate(0, 0)\"><polygon fill=\"none\" stroke=\"#f5a623\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-miterlimit=\"10\" points=\"12,2.6 15,9 21.4,9 16.7,13.9 18.6,21.4 12,17.6 5.4,21.4 7.3,13.9 2.6,9 9,9 \" stroke-linejoin=\"miter\"\/><\/g><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\">No ratings yet<\/div><\/div>\n<div class=\"wprm-spacer\" style=\"height: 25px;\"><\/div>\n<div class=\"wprm-template-chic-buttons wprm-container-columns-spaced-middle wprm-container-columns-gutter\">\n\t<a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/wprm_print\/pepian-o-pipian-verde-con-pavo\" style=\"color: #ffffff;background-color: #f5a623;border-color: #f5a623;border-radius: 3px;padding: 10px 5px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-wide-button wprm-recipe-link-wide-button wprm-color-accent\" data-recipe-id=\"23298\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#ffffff\"><g><path d=\"M17.5454,0.0005 C18.2904,0.0005 18.9004,0.6105 18.9004,1.3565 L18.9004,1.3565 L18.9004,4.9445 L21.9904,4.9445 C23.0954,4.9445 24.0004,5.8485 24.0004,6.9535 L24.0004,6.9535 L24.0004,17.2415 C24.0004,18.3465 23.0954,19.2505 21.9904,19.2505 L21.9904,19.2505 L19.8414,19.2505 L19.8414,22.2795 C19.8414,23.1725 19.1104,23.9035 18.2174,23.9035 L18.2174,23.9035 L5.7834,23.9035 C4.8894,23.9035 4.1594,23.1725 4.1594,22.2795 L4.1594,22.2795 L4.1594,19.2505 L2.0104,19.2505 C0.9044,19.2505 0.0004,18.3465 0.0004,17.2415 L0.0004,17.2415 L0.0004,6.9535 C0.0004,5.8485 0.9044,4.9445 2.0104,4.9445 L2.0104,4.9445 L5.0984,4.9445 L5.0984,1.3565 C5.0984,0.6105 5.7094,0.0005 6.4554,0.0005 L6.4554,0.0005 Z M17.8414,15.5975 L6.1594,15.5975 L6.1594,21.9035 L17.8414,21.9035 L17.8414,15.5975 Z M21.9904,6.9445 L2.0104,6.9445 L2.0004,17.2415 L4.1594,17.2425 L4.1594,15.2215 C4.1594,14.3285 4.8894,13.5975 5.7834,13.5975 L5.7834,13.5975 L18.2174,13.5975 C19.1104,13.5975 19.8414,14.3285 19.8414,15.2215 L19.8414,15.2215 L19.8414,17.2495 L21.9904,17.2505 L22.0004,6.9535 L21.9904,6.9445 Z M6.1632,9.1318 C6.7902,9.1318 7.2992,9.6408 7.2992,10.2678 C7.2992,10.8948 6.7902,11.4028 6.1632,11.4028 L6.1632,11.4028 L5.0992,11.4028 C4.4722,11.4028 3.9632,10.8948 3.9632,10.2678 C3.9632,9.6408 4.4722,9.1318 5.0992,9.1318 L5.0992,9.1318 Z M16.6304,2.2715 L7.3704,2.2715 L7.3704,4.6845 L16.6304,4.6845 L16.6304,2.2715 Z\"><\/path><\/g><\/g><\/g><\/svg><\/span> Imprimir receta<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.adrianasbestrecipes.com%2Fes%2Fpepian-o-pipian-verde-con-pavo%2F&amp;media=https%3A%2F%2Fwww.adrianasbestrecipes.com%2Fwp-content%2Fuploads%2F2017%2F11%2FGreen-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg&amp;description=El+pepian+o+pipi%C3%A1n+cocinado+con+la+t%C3%A9cnica+sous+vide.+La+salsa+est%C3%A1+hecha+con+pepitas+de+calabaza+y+condimentos+especiales+como+el+epazote+y+el+comino.+El+pepian+o+pipi%C3%A1n+tambi%C3%A9n+es+llamado+mole+verde+y+es+una+salsa+muy+especial.+Esta+receta+es+corresponde+a+la+cocina+mexicana+cl%C3%A1sica.++%23CocinaMexicana+%23pepiandepavo+%23pipian+%23moleverde&amp;is_video=false\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"23298\" data-url=\"https:\/\/www.adrianasbestrecipes.com\/es\/pepian-o-pipian-verde-con-pavo\/\" data-media=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg\" data-description=\"El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino. El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Esta receta es corresponde a la cocina mexicana cl\u00e1sica.  #CocinaMexicana #pepiandepavo #pipian #moleverde\" data-repin=\"\" role=\"button\" style=\"color: #616161;background-color: #ffffff;border-color: #616161;border-radius: 3px;padding: 10px 5px;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal wprm-recipe-pin-wide-button wprm-recipe-link-wide-button wprm-color-accent\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg width=\"17px\" height=\"20px\" viewBox=\"0 0 17 20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-4.000000, -2.000000)\" fill=\"#616161\"><path d=\"M10.7636728,15.2276266 C10.2077317,17.980299 9.52955405,20.6201377 7.52087891,22 C6.90029349,17.8380815 8.43177606,14.7128228 9.14286352,11.3948064 C7.93107647,9.46487979 9.28860706,5.58269488 11.8449959,6.53943073 C14.9902356,7.71595725 9.12053185,13.7114236 13.0614843,14.4612976 C17.1752134,15.2429061 18.8547902,7.71125585 16.3042782,5.26182401 C12.6183769,1.72519235 5.57332202,5.18072478 6.43955583,10.2441376 C6.65111904,11.4829577 8.00277289,11.8578948 6.98021737,13.5668554 C4.62128758,13.0720325 3.91607687,11.3125318 4.00775427,8.9665309 C4.15349781,5.12783398 7.65604429,2.43980586 11.1691689,2.06721954 C15.6119964,1.59707907 19.7821423,3.61045562 20.3580644,7.56198625 C21.0056829,12.0224439 18.3529153,16.8531372 13.6009705,16.5052333 C12.313961,16.4100298 11.7732994,15.8070747 10.7636728,15.2276266\"><\/path><\/g><\/g><\/svg><\/span> Fijar la receta<\/a>\n    \n<\/div>\n<div class=\"wprm-spacer\" style=\"height: 20px;\"><\/div>\n<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><g><path d=\"M12,0 C18.627,0 24,4.373 24,11 C24,19.406 18.646,24 18.646,24 L18.646,24 L5.354,24 C5.354,24 0,19.406 0,11 C0,4.373 5.373,0 12,0 Z M12,2 C6.206,2 2,5.785 2,11 C2,16.956 4.962,20.716 6.168,22 L6.168,22 L17.832,22 C19.032,20.724 22,16.962 22,11 C22,5.785 17.794,2 12,2 Z M15.4175,17.7983 C15.9697847,17.7983 16.4175,18.2460153 16.4175,18.7983 C16.4175,19.3111358 16.0314598,19.7338072 15.5341211,19.7915723 L15.4175,19.7983 L8.5825,19.7983 C8.03021525,19.7983 7.5825,19.3505847 7.5825,18.7983 C7.5825,18.2854642 7.96854019,17.8627928 8.46587887,17.8050277 L8.5825,17.7983 L15.4175,17.7983 Z M12,4.2544 C15.173,4.2544 17.746,6.8264 17.746,10.0004 C17.746,13.1734 15.173,15.7454 12,15.7454 C8.827,15.7454 6.254,13.1734 6.254,10.0004 C6.254,6.8264 8.827,4.2544 12,4.2544 Z M10.9999773,6.38993761 C9.41864646,6.82850486 8.254,8.28073633 8.254,10.0004 C8.254,12.0654 9.935,13.7454 12,13.7454 C14.065,13.7454 15.746,12.0654 15.746,10.0004 C15.746,8.28110051 14.5818468,6.82911997 13.0010273,6.39021638 L13,9.2962 C13,9.84848475 12.5522847,10.2962 12,10.2962 C11.4871642,10.2962 11.0644928,9.91015981 11.0067277,9.41282113 L11,9.2962 Z\"><\/path><\/g><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Tiempo de preparaci\u00f3n <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">15<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-time-label wprm-recipe-cook-time-label\">Tiempo de cocci\u00f3n <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-hours wprm-recipe-cook_time wprm-recipe-cook_time-hours\">2<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> horas<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-unit-hours wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-hours\" aria-hidden=\"true\">horas<\/span><\/span><\/div><\/div>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-container-columns-spaced\">\n\t<div>\n    \t<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M19.5441,12.0586 L17.8411,12.3146 L17.8411,14.0376 L17.8411,17.8606 L6.1591,17.8606 L6.1591,14.0376 L6.1591,12.3146 L4.4561,12.0586 C3.0331,11.8446 2.0001,10.6536 2.0001,9.2246 C2.0001,7.6626 3.2471,6.3876 4.7971,6.3406 C4.8651,6.3486 4.9351,6.3556 5.0051,6.3576 L6.3221,6.4136 L6.8931,5.2246 C7.8481,3.2356 9.8051,1.9996 12.0001,1.9996 C14.1951,1.9996 16.1521,3.2356 17.1071,5.2246 L17.6781,6.4136 L18.9951,6.3576 C19.0641,6.3556 19.1321,6.3486 19.2021,6.3406 C20.7531,6.3866 22.0001,7.6626 22.0001,9.2246 C22.0001,10.6536 20.9671,11.8446 19.5441,12.0586 L19.5441,12.0586 Z M6.1591,22.0006 L17.8411,22.0006 L17.8411,19.8606 L6.1591,19.8606 L6.1591,22.0006 Z M19.1141,4.3386 C19.0451,4.3386 18.9801,4.3566 18.9101,4.3596 C17.6741,1.7836 15.0491,-0.0004 12.0001,-0.0004 C8.9511,-0.0004 6.3261,1.7836 5.0901,4.3596 C5.0211,4.3566 4.9551,4.3386 4.8861,4.3386 C2.1881,4.3386 0.0001,6.5266 0.0001,9.2246 C0.0001,11.6736 1.8081,13.6836 4.1591,14.0376 L4.1591,22.3756 C4.1591,23.2696 4.8901,23.9996 5.7831,23.9996 L18.2171,23.9996 C19.1101,23.9996 19.8411,23.2696 19.8411,22.3756 L19.8411,14.0376 C22.1911,13.6836 24.0001,11.6736 24.0001,9.2246 C24.0001,6.5266 21.8131,4.3386 19.1141,4.3386 L19.1141,4.3386 Z\" id=\"Fill-1\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-course-label\">Plato <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Platillo Principal<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cocina <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">Cocina Mexicana<\/span><\/div><\/div>\n    <\/div>\n    <div>\n        <div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M15.9199,4.9443 L18.1399,2.7243 C18.5509,2.3133 19.0909,2.1083 19.6299,2.1083 C20.1699,2.1083 20.7099,2.3133 21.1209,2.7243 C21.9429,3.5473 21.9419,4.8843 21.1209,5.7073 L18.9019,7.9253 C18.0799,8.7483 16.7419,8.7483 15.9199,7.9253 C15.0979,7.1033 15.0979,5.7663 15.9199,4.9443 M23.5529,22.1383 L13.3369,11.9233 L15.3109,9.9493 C15.9559,10.3353 16.6809,10.5413 17.4109,10.5413 C18.4629,10.5413 19.5159,10.1403 20.3159,9.3403 L22.5349,7.1213 C24.1369,5.5183 24.1369,2.9123 22.5349,1.3103 C21.7599,0.5343 20.7279,0.1073 19.6299,0.1073 C18.5329,0.1073 17.5019,0.5343 16.7259,1.3103 L14.5059,3.5303 C13.7299,4.3063 13.3029,5.3383 13.3029,6.4343 C13.3029,7.1883 13.5179,7.9053 13.8959,8.5363 L11.9229,10.5083 L9.9489,8.5353 C10.8909,6.9593 10.6959,4.8863 9.3399,3.5303 L6.1039,0.2933 C5.7129,-0.0977 5.0799,-0.0977 4.6899,0.2933 C4.2989,0.6833 4.2989,1.3163 4.6899,1.7073 L7.9259,4.9443 C8.4909,5.5093 8.6579,6.3153 8.4459,7.0323 L3.6539,2.2403 C3.2639,1.8493 2.6309,1.8493 2.2399,2.2403 C1.8499,2.6313 1.8499,3.2633 2.2399,3.6543 L7.0319,8.4463 C6.3149,8.6583 5.5089,8.4913 4.9429,7.9253 L1.7069,4.6893 C1.3159,4.2983 0.6839,4.2983 0.2929,4.6893 C-0.0981,5.0803 -0.0981,5.7133 0.2929,6.1033 L3.5289,9.3403 C4.3309,10.1403 5.3829,10.5413 6.4349,10.5413 C7.1649,10.5413 7.8899,10.3353 8.5349,9.9493 L10.5089,11.9233 L0.2929,22.1383 C-0.0981,22.5293 -0.0981,23.1623 0.2929,23.5523 C0.4879,23.7483 0.7439,23.8453 0.9999,23.8453 C1.2559,23.8453 1.5119,23.7483 1.7069,23.5523 L11.9229,13.3373 L22.1389,23.5523 C22.3339,23.7483 22.5899,23.8453 22.8459,23.8453 C23.1019,23.8453 23.3569,23.7483 23.5529,23.5523 C23.9429,23.1623 23.9429,22.5293 23.5529,22.1383\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-servings-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-servings-label\">Raciones <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-23298 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"23298\" aria-label=\"Adjust recipe servings\">6<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">porciones<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-nutrition-container wprm-recipe-calories-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-nutrition-label wprm-recipe-calories-label\">Calor\u00edas <\/span><span class=\"wprm-recipe-nutrition-with-unit\"><span class=\"wprm-recipe-details wprm-recipe-nutrition wprm-recipe-calories wprm-block-text-normal\">372<\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-nutrition-unit wprm-recipe-calories-unit wprm-block-text-normal\">kcal<\/span><\/span><\/div><\/div>\n    <\/div>\n<\/div>\n<div id=\"recipe-23298-equipment\" class=\"wprm-recipe-equipment-container wprm-block-text-normal\" data-recipe=\"23298\"><h3 class=\"wprm-recipe-header wprm-recipe-equipment-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">Equipo<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-spacer\" style=\"height: 22px;\"><\/div><ul class=\"wprm-recipe-equipment wprm-recipe-equipment-list\"><li class=\"wprm-recipe-equipment-item\" style=\"list-style-type: disc;\"><div class=\"wprm-recipe-equipment-name\">Sous Vide<\/div><\/li><li class=\"wprm-recipe-equipment-item\" style=\"list-style-type: disc;\"><div class=\"wprm-recipe-equipment-name\">Comal<\/div><\/li><li class=\"wprm-recipe-equipment-item\" style=\"list-style-type: disc;\"><div class=\"wprm-recipe-equipment-name\">Licuadora<\/div><\/li><\/ul><\/div>\n<div id=\"recipe-23298-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-23298-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"23298\" data-servings=\"6\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line wprm-header-has-actions wprm-header-has-actions\" style=\"\">Ingredientes<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div>&nbsp;&nbsp;<div class=\"wprm-recipe-adjustable-servings-container wprm-recipe-adjustable-servings-23298-container wprm-toggle-container wprm-toggle-buttons-container wprm-block-text-normal\" style=\"--wprm-toggle-button-accent: #616161;\"><button class=\"wprm-recipe-adjustable-servings wprm-toggle wprm-toggle-active\" data-multiplier=\"1\" data-servings=\"6\" data-recipe=\"23298\" aria-label=\"Adjust servings by 1x\">1x<\/button><button class=\"wprm-recipe-adjustable-servings wprm-toggle\" data-multiplier=\"2\" data-servings=\"6\" data-recipe=\"23298\" aria-label=\"Adjust servings by 2x\">2x<\/button><button class=\"wprm-recipe-adjustable-servings wprm-toggle\" data-multiplier=\"3\" data-servings=\"6\" data-recipe=\"23298\" aria-label=\"Adjust servings by 3x\">3x<\/button><\/div><\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1.5<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">libras<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">carne blanca de pavo<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">tenderloin o la pechuga<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1\/2<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">aceite de oliva<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharada<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">sazon latino<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharadita<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">ajo en polvo<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharadita<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">pimienta negra<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">pepitas<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharada <\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">epazote<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">seco o 4 hojitas de epazote fresco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharadita<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">comino entero<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">10<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">tomatillos<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">limpios y sin c\u00e1scara<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">dientes de ajo<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">5<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">chiles serranos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">agua<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"-1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cucharada<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">caldo de pollo en polvo<\/span><\/li><\/ul><\/div><\/div>\n<div id=\"recipe-23298-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-23298-instructions-container wprm-block-text-normal\" data-recipe=\"23298\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line wprm-header-has-actions\" style=\"\">Instrucciones<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div>&nbsp;<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-23298-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Sazona el pavo con aceite de oliva, saz\u00f3n latino, ajo en polvo y pimienta. Coloca el pavo en la bolsa de pl\u00e1stico y sella. Agregue agua al sous vide y ajusta a una temperatura de 150 grados Fahrenheit. Agrega el pavo al ba\u00f1o de agua y coc\u00ednalo durante 2 horas.<\/div><\/li><li id=\"wprm-recipe-23298-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Limpia las verduras y lava con agua corriente. Coloca un comal o una sart\u00e9n en la estufa y tuesta los tomatillos, el ajo fresco y los serranos. Agregua agua a una olla y cocina las verduras asadas hasta que est\u00e9n tiernas.<\/div><\/li><li id=\"wprm-recipe-23298-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Tuesta las pepitas en la misma sart\u00e9n. Aseg\u00farate de no quemarlas. Solo tuesta  ligeramente. Haz lo mismo con el epazote y las semillas de comino. Tostar los condimentos permite desarrollar un sabor m\u00e1s profundo.<\/div><\/li><li id=\"wprm-recipe-23298-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Agrega las verduras cocidas a la licuadora y vierte un poco de agua de cocci\u00f3n. Agregue las pepitas asadas, el epazote y el comino. Y sazona con caldo de pollo en polvo. Mezcla hasta obtener una salsa sedosa.<\/div><\/li><li id=\"wprm-recipe-23298-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Saca el pavo del horno de agua y corta. Agrega el pepian verde y acompa\u00f1a el platillo con arroz blanco. Puedes decorar con pepitas tostadas y cilantro.<\/div><\/li><\/ul><\/div><\/div>\n<div id=\"recipe-video\"><\/div><div id=\"wprm-recipe-video-container-23298\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">V\u00eddeo<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-recipe-video\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/2dLRktIZrPk\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/div>\n<div id=\"recipe-23298-notes\" class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">Notas<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-recipe-notes\"><span style=\"display: block;\">Sirve el pavo en pepian verde con tortillas de ma\u00edz calientitas. Coloca un taz\u00f3n en la mesa\u00a0con m\u00e1s salsa de pepian para que los comensales se sirvan m\u00e1s si desean.<\/span><\/div><\/div>\n<div id=\"recipe-23298-nutrition\" class=\"wprm-nutrition-label-shortcode-container\"><h3 class=\"wprm-recipe-header wprm-recipe-nutrition-header wprm-block-text-uppercase wprm-align-left wprm-header-decoration-line\" style=\"\">Nutrici\u00f3n<div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/h3><div class=\"wprm-nutrition-label-container wprm-nutrition-label-container-grouped wprm-block-text-normal wprm-nutrition-label-container-grouped-text\" style=\"text-align: left;column-gap: 10px;\"><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-serving_size\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Raci\u00f3n: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">6<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-calories\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Calor\u00edas: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">372<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">kcal<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-carbohydrates\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Carbohidratos: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">8<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-protein\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Proteina: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">31<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">26<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-saturated_fat\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Grasa saturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">4<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-cholesterol\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Colesterol: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">51<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sodium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Sodio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">93<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-potassium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Potasio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">306<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fiber\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Fibra: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">3<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sugar\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Az\u00facar: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">3<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_a\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Vitamina A: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">153<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">IU<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_c\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Vitamina C: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">10<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-calcium\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Calcio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">60<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-iron\"style=\"flex-basis: 175px;\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-faded\" style=\"color: #333333\">Hierro: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">3<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-empty\" style=\"flex-basis: 175px\"><\/span><\/div><\/div>\n<div class=\"wprm-spacer\" style=\"height: 20px;\"><\/div>\n<div class=\"wprm-icon-shortcode wprm-icon-shortcode-separate wprm-align-center wprm-icon-decoration-line\" style=\"font-size: 24px;height: 24px;\"><div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><span class=\"wprm-recipe-icon\" aria-hidden=\"true\"><svg width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g id=\"Icons\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g fill=\"#9e9e9e\"><path d=\"M9.0039,16.0079 C5.1419,16.0079 1.9999,12.8659 1.9999,9.0039 C1.9999,5.1419 5.1419,1.9999 9.0039,1.9999 C12.8659,1.9999 16.0079,5.1419 16.0079,9.0039 C16.0079,12.8659 12.8659,16.0079 9.0039,16.0079 M23.6209,22.2069 L16.1439,14.7299 C16.1059,14.6919 16.0579,14.6759 16.0159,14.6449 C17.2599,13.1009 18.0079,11.1409 18.0079,9.0039 C18.0079,4.0309 13.9769,-0.0001 9.0039,-0.0001 C4.0309,-0.0001 -0.0001,4.0309 -0.0001,9.0039 C-0.0001,13.9769 4.0309,18.0079 9.0039,18.0079 C11.1409,18.0079 13.1009,17.2599 14.6449,16.0169 C14.6749,16.0579 14.6919,16.1059 14.7299,16.1439 L22.2069,23.6209 C22.4019,23.8169 22.6579,23.9139 22.9139,23.9139 C23.1699,23.9139 23.4259,23.8169 23.6209,23.6209 C24.0119,23.2309 24.0119,22.5979 23.6209,22.2069\"><\/path><\/g><\/g><\/svg><\/span> <div class=\"wprm-decoration-line\" style=\"border-color: #e0e0e0;\"><\/div><\/div>\n<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-table wprm-block-text-normal wprm-recipe-table-borders-none wprm-recipe-table-borders-inside\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-table wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"border-width: 0;border-style: dotted;border-color: #666666;\"><span class=\"wprm-recipe-details-label wprm-block-text-uppercase-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Palabra clave <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">pavo, pepitas, sous vide<\/span><\/div><\/div>\n<div class=\"wprm-spacer\"><\/div>\n<div class=\"wprm-call-to-action wprm-call-to-action-simple\" style=\"color: #ffffff;background-color: #f5a623;margin: 0px;padding-top: 30px;padding-bottom: 30px;\"><span class=\"wprm-recipe-icon wprm-call-to-action-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#ffffff\"><path fill=\"#ffffff\" d=\"M12,2.162c3.204,0,3.584,0.012,4.849,0.07c1.366,0.062,2.633,0.336,3.608,1.311 c0.975,0.975,1.249,2.242,1.311,3.608c0.058,1.265,0.07,1.645,0.07,4.849s-0.012,3.584-0.07,4.849 c-0.062,1.366-0.336,2.633-1.311,3.608c-0.975,0.975-2.242,1.249-3.608,1.311c-1.265,0.058-1.645,0.07-4.849,0.07 s-3.584-0.012-4.849-0.07c-1.366-0.062-2.633-0.336-3.608-1.311c-0.975-0.975-1.249-2.242-1.311-3.608 c-0.058-1.265-0.07-1.645-0.07-4.849s0.012-3.584,0.07-4.849c0.062-1.366,0.336-2.633,1.311-3.608 c0.975-0.975,2.242-1.249,3.608-1.311C8.416,2.174,8.796,2.162,12,2.162 M12,0C8.741,0,8.332,0.014,7.052,0.072 c-1.95,0.089-3.663,0.567-5.038,1.942C0.639,3.389,0.161,5.102,0.072,7.052C0.014,8.332,0,8.741,0,12 c0,3.259,0.014,3.668,0.072,4.948c0.089,1.95,0.567,3.663,1.942,5.038c1.375,1.375,3.088,1.853,5.038,1.942 C8.332,23.986,8.741,24,12,24s3.668-0.014,4.948-0.072c1.95-0.089,3.663-0.567,5.038-1.942c1.375-1.375,1.853-3.088,1.942-5.038 C23.986,15.668,24,15.259,24,12s-0.014-3.668-0.072-4.948c-0.089-1.95-0.567-3.663-1.942-5.038 c-1.375-1.375-3.088-1.853-5.038-1.942C15.668,0.014,15.259,0,12,0L12,0z\"><\/path> <path data-color=\"color-2\" d=\"M12,5.838c-3.403,0-6.162,2.759-6.162,6.162S8.597,18.162,12,18.162s6.162-2.759,6.162-6.162 S15.403,5.838,12,5.838z M12,16c-2.209,0-4-1.791-4-4s1.791-4,4-4s4,1.791,4,4S14.209,16,12,16z\"><\/path> <circle data-color=\"color-2\" cx=\"18.406\" cy=\"5.594\" r=\"1.44\"><\/circle><\/g><\/svg><\/span> <span class=\"wprm-call-to-action-text-container\"><span class=\"wprm-call-to-action-header\" style=\"color: #ffffff;\">\u00bfHas probado esta receta?<\/span><span class=\"wprm-call-to-action-text\">Mention <a href=\"https:\/\/www.instagram.com\/adrianasbestrecipes\" target=\"_blank\" rel=\"noreferrer noopener\" style=\"color: #ffffff\">@adrianasbestrecipes<\/a> or tag <a href=\"https:\/\/www.instagram.com\/explore\/tags\/abrecipes\" target=\"_blank\" rel=\"noreferrer noopener\" style=\"color: #ffffff\">#abrecipes<\/a> on Instagram<\/span><\/span><\/div><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00edguenos en Instagram en <a href=\"https:\/\/www.instagram.com\/adrianasbestrecipes\/\" target=\"_blank\" rel=\"noopener\" aria-label=\"@adrianasbestrecipes (opens in a new tab)\">@adrianasbestrecipes<\/a>, publicamos recetas deliciosas todos los d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote.<\/p>\n","protected":false},"author":2,"featured_media":17634,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"sous vide,Pepian","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[66,15987,628,513],"tags":[],"class_list":["post-17616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cena-2","category-cocina-sous-vide","category-cultura","category-videos","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_featured_media_url":"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg","spectra_custom_meta":{"_edit_lock":["1606030219:2"],"_edit_last":["2"],"_alp_processed":["1530183135"],"_yoast_wpseo_content_score":["30"],"swp_advanced_pinterest_image":["default"],"swp_advanced_pinterest_image_location":["default"],"swp_post_location":["default"],"swp_float_location":["default"],"twitterID":["ABRecipes"],"true":["true"],"recipe_custom_template":["default"],"recipe_title":["Pepi\u00e1n o Pipi\u00e1n Verde con Pavo"],"recipe_rating":["0"],"recipe_servings_normalized":["6"],"recipe_ingredients":["a:13:{i:0;a:7:{s:6:\"amount\";s:3:\"1.5\";s:4:\"unit\";s:6:\"libras\";s:10:\"ingredient\";s:20:\"carne blanca de pavo\";s:5:\"notes\";s:23:\"tenderloin o la pechuga\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5581;s:17:\"amount_normalized\";d:1.5;}i:1;a:7:{s:6:\"amount\";s:3:\"1\/2\";s:4:\"unit\";s:4:\"taza\";s:10:\"ingredient\";s:15:\"aceite de oliva\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5244;s:17:\"amount_normalized\";d:0.5;}i:2;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:9:\"cucharada\";s:10:\"ingredient\";s:12:\"sazon latino\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5186;s:17:\"amount_normalized\";d:1;}i:3;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:11:\"cucharadita\";s:10:\"ingredient\";s:12:\"ajo en polvo\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5279;s:17:\"amount_normalized\";d:1;}i:4;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:11:\"cucharadita\";s:10:\"ingredient\";s:14:\"pimienta negra\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5216;s:17:\"amount_normalized\";d:1;}i:5;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:4:\"taza\";s:10:\"ingredient\";s:7:\"pepitas\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5582;s:17:\"amount_normalized\";d:1;}i:6;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:10:\"cucharada \";s:10:\"ingredient\";s:7:\"epazote\";s:5:\"notes\";s:34:\"seco o 4 hojitas de epazote fresco\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5569;s:17:\"amount_normalized\";d:1;}i:7;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:11:\"cucharadita\";s:10:\"ingredient\";s:13:\"comino entero\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5583;s:17:\"amount_normalized\";d:1;}i:8;a:7:{s:6:\"amount\";s:2:\"10\";s:4:\"unit\";s:0:\"\";s:10:\"ingredient\";s:10:\"tomatillos\";s:5:\"notes\";s:22:\"limpios y sin c\u00e1scara\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5375;s:17:\"amount_normalized\";d:10;}i:9;a:7:{s:6:\"amount\";s:1:\"2\";s:4:\"unit\";s:0:\"\";s:10:\"ingredient\";s:14:\"dientes de ajo\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:4215;s:17:\"amount_normalized\";d:2;}i:10;a:7:{s:6:\"amount\";s:1:\"5\";s:4:\"unit\";s:0:\"\";s:10:\"ingredient\";s:15:\"chiles serranos\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5021;s:17:\"amount_normalized\";d:5;}i:11;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:4:\"taza\";s:10:\"ingredient\";s:4:\"agua\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5249;s:17:\"amount_normalized\";d:1;}i:12;a:7:{s:6:\"amount\";s:1:\"1\";s:4:\"unit\";s:9:\"cucharada\";s:10:\"ingredient\";s:23:\"caldo de pollo en polvo\";s:5:\"notes\";s:0:\"\";s:5:\"group\";s:0:\"\";s:13:\"ingredient_id\";i:5584;s:17:\"amount_normalized\";d:1;}}"],"recipe_instructions":["a:5:{i:0;a:3:{s:11:\"description\";s:264:\"Sazona el pavo con aceite de oliva, saz\u00f3n latino, ajo en polvo y pimienta. Coloca el pavo en la bolsa de pl\u00e1stico y sella. Agregue agua al sous vide y ajusta a una temperatura de 150 grados Fahrenheit. Agrega el pavo al ba\u00f1o de agua y coc\u00ednalo durante 2 horas.\";s:5:\"group\";s:0:\"\";s:5:\"image\";s:0:\"\";}i:1;a:3:{s:11:\"description\";s:225:\"Limpia las verduras y lava con agua corriente. Coloca un comal o una sart\u00e9n en la estufa y tuesta los tomatillos, el ajo fresco y los serranos. Agregua agua a una olla y cocina las verduras asadas hasta que est\u00e9n tiernas.\r\n\";s:5:\"group\";s:0:\"\";s:5:\"image\";s:0:\"\";}i:2;a:3:{s:11:\"description\";s:215:\"Tuesta las pepitas en la misma sart\u00e9n. Aseg\u00farate de no quemarlas. Solo tuesta  ligeramente. Haz lo mismo con el epazote y las semillas de comino. Tostar los condimentos permite desarrollar un sabor m\u00e1s profundo. \";s:5:\"group\";s:0:\"\";s:5:\"image\";s:0:\"\";}i:3;a:3:{s:11:\"description\";s:210:\"Agrega las verduras cocidas a la licuadora y vierte un poco de agua de cocci\u00f3n. Agregue las pepitas asadas, el epazote y el comino. Y sazona con caldo de pollo en polvo. Mezcla hasta obtener una salsa sedosa. \";s:5:\"group\";s:0:\"\";s:5:\"image\";s:0:\"\";}i:4;a:3:{s:11:\"description\";s:154:\"Saca el pavo del horno de agua y corta. Agrega el pepian verde y acompa\u00f1a el platillo con arroz blanco. Puedes decorar con pepitas tostadas y cilantro.\r\n\";s:5:\"group\";s:0:\"\";s:5:\"image\";s:0:\"\";}}"],"recipe_terms":["a:5:{s:10:\"ingredient\";a:14:{i:0;i:0;i:1;i:5244;i:2;i:5249;i:3;i:5279;i:4;i:5584;i:5;i:5581;i:6;i:5021;i:7;i:5583;i:8;i:4215;i:9;i:5569;i:10;i:5582;i:11;i:5216;i:12;i:5186;i:13;i:5375;}s:6:\"course\";a:2:{i:0;i:0;i:1;i:3251;}s:7:\"cuisine\";a:2:{i:0;i:0;i:1;i:2806;}s:8:\"category\";a:4:{i:0;i:0;i:1;i:66;i:2;i:628;i:3;i:513;}s:8:\"post_tag\";a:1:{i:0;i:0;}}"],"recipe_terms_with_parents":["a:5:{s:10:\"ingredient\";a:14:{i:0;i:0;i:1;i:5244;i:2;i:5249;i:3;i:5279;i:4;i:5584;i:5;i:5581;i:6;i:5021;i:7;i:5583;i:8;i:4215;i:9;i:5569;i:10;i:5582;i:11;i:5216;i:12;i:5186;i:13;i:5375;}s:6:\"course\";a:2:{i:0;i:0;i:1;i:3251;}s:7:\"cuisine\";a:2:{i:0;i:0;i:1;i:2806;}s:8:\"category\";a:4:{i:0;i:0;i:1;i:66;i:2;i:628;i:3;i:513;}s:8:\"post_tag\";a:1:{i:0;i:0;}}"],"_yoast_wpseo_primary_course":["3251"],"_yoast_wpseo_primary_cuisine":["2806"],"wpurp_text_search_3":["1511935647"],"_yoast_wpseo_focuskw_text_input":["Pepian"],"_yoast_wpseo_focuskw":["Pepian"],"_yoast_wpseo_metadesc":["El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino."],"_yoast_wpseo_linkdex":["82"],"easyrecipe_author":["Chef Adriana Martin"],"_thumbnail_id":["17634"],"swp_custom_tweet":["El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Conoce los detalles. "],"swp_pinterest_description":["El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote."],"recipe_description":["El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote. El pepian va muy bien con aves o con carne de puerco. "],"recipe_servings":["6"],"recipe_servings_type":["porciones"],"recipe_prep_time":["15 "],"recipe_prep_time_text":["minutos"],"recipe_cook_time":["2"],"recipe_cook_time_text":["horas"],"recipe_notes":["Sirve el pavo en pepian verde con tortillas de ma\u00edz calientitas. Coloca un taz\u00f3n en la mesa\u00a0con m\u00e1s salsa de pepian para que los comensales se sirvan m\u00e1s si desean."],"swp_pinterest_image":["17631"],"_totes":["110"],"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":807,\"es\":807}}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["0"],"wprm_rating":["a:4:{s:5:\"count\";i:0;s:5:\"total\";i:0;s:7:\"average\";i:0;s:4:\"type\";a:3:{s:7:\"comment\";i:0;s:10:\"no_comment\";i:0;s:4:\"user\";i:0;}}"],"wprm_rating_average":["0"],"bitly_link":["http:\/\/bit.ly\/2MZkBkY"],"_google_plus_shares":["0"],"bitly_link_google_plus":["http:\/\/bit.ly\/2KL2KNb"],"swp_open_graph_image_data":["false"],"swp_open_graph_image_url":[""],"_facebook_shares":["8"],"_pinterest_shares":["102"],"_buffer_shares":["0"],"_yummly_shares":["0"],"_twitter_shares":["0"],"_whatsapp_shares":["0"],"_flipboard_shares":["0"],"_mix_shares":["0"],"_email_shares":["0"],"_total_shares":["110"],"swp_pinterest_image_data":["[\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg\",750,1613,false]"],"swp_pinterest_image_url":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg"],"bitly_link_facebook":["http:\/\/bit.ly\/2u9V8h8"],"bitly_link_twitter":["http:\/\/bit.ly\/2ubEHks"],"bitly_link_mix":["http:\/\/bit.ly\/2ubEfmg"],"bitly_link_buffer":["http:\/\/bit.ly\/2ucQeA2"],"bitly_link_flipboard":["http:\/\/bit.ly\/2ubEJc4"],"bitly_link_email":["http:\/\/bit.ly\/2ubEKwE"],"bitly_link_whatsapp":["http:\/\/bit.ly\/2uc8FVH"],"bitly_link_yummly":["http:\/\/bit.ly\/2u9w9L1"],"swp_cache_timestamp":["431317"],"dpsp_share_options":["a:6:{s:12:\"custom_image\";a:2:{s:2:\"id\";s:0:\"\";s:3:\"src\";s:0:\"\";}s:12:\"custom_title\";s:0:\"\";s:18:\"custom_description\";s:0:\"\";s:22:\"custom_image_pinterest\";a:2:{s:2:\"id\";s:5:\"17631\";s:3:\"src\";s:226:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg\";}s:28:\"custom_description_pinterest\";s:342:\"El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino. El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Esta receta es corresponde a la cocina mexicana cl\u00e1sica.  #CocinaMexicana #pepiandepavo #pipian #moleverde\";s:12:\"custom_tweet\";s:101:\"El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Conoce los detalles. \";}"],"dpsp_networks_shares":["a:7:{s:8:\"facebook\";i:8;s:9:\"pinterest\";i:102;s:7:\"twitter\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;s:4:\"grow\";i:1;}"],"dpsp_networks_shares_total":["111"],"dpsp_networks_shares_last_updated":["1643480085"],"dpsp_cache_shares_twitter_2":["0"],"_jetpack_related_posts_cache":["a:1:{s:32:\"8f6677c9d6b0f903e98ad32ec61f8deb\";a:2:{s:7:\"expires\";i:1622110950;s:7:\"payload\";a:3:{i:0;a:1:{s:2:\"id\";i:24946;}i:1;a:1:{s:2:\"id\";i:21235;}i:2;a:1:{s:2:\"id\";i:17723;}}}}"],"_genesis_scripts_body_position":["bottom"],"dpsp_post_single_previous_urls":["a:0:{}"],"_yoast_wpseo_focuskeywords":["[{\"keyword\":\"sous vide\",\"score\":\"good\"}]"],"_yoast_wpseo_keywordsynonyms":["[\"pipian\",\"\"]"],"dpsp_short_link_bitly":["a:14:{s:18:\"facebook_short_url\";s:21:\"http:\/\/bit.ly\/2IlqgCQ\";s:17:\"twitter_short_url\";s:21:\"http:\/\/bit.ly\/2Ild159\";s:18:\"whatsapp_short_url\";s:21:\"http:\/\/bit.ly\/2IlpQfK\";s:16:\"yummly_short_url\";s:21:\"http:\/\/bit.ly\/2Ild2pJ\";s:15:\"email_short_url\";s:21:\"http:\/\/bit.ly\/2Ild4hl\";s:13:\"mix_short_url\";s:21:\"http:\/\/bit.ly\/2MBYl1O\";s:19:\"flipboard_short_url\";s:21:\"http:\/\/bit.ly\/2VOZUxJ\";s:18:\"linkedin_short_url\";s:21:\"http:\/\/bit.ly\/32kJZd8\";s:16:\"reddit_short_url\";s:21:\"http:\/\/bit.ly\/2VKuVmD\";s:16:\"buffer_short_url\";s:21:\"http:\/\/bit.ly\/2Bas9gW\";s:18:\"telegram_short_url\";s:21:\"http:\/\/bit.ly\/35DUji8\";s:14:\"grow_short_url\";s:22:\"https:\/\/bit.ly\/3ushmsn\";s:17:\"threads_short_url\";s:22:\"https:\/\/bit.ly\/3xknbPp\";s:18:\"mastodon_short_url\";s:22:\"https:\/\/bit.ly\/3xvqLWU\";}"],"dpsp_post_previous_urls":["a:1:{i:0;s:81:\"https:\/\/www.adrianasbestrecipes.com\/es\/2017\/11\/09\/pepian-o-pipian-verde-con-pavo\/\";}"],"dpsp_networks_shares_previous_urls":["a:5:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;}"],"_tbf_fix_details":["a:5:{s:6:\"fix_id\";s:4:\"5097\";s:19:\"changed_revision_id\";s:5:\"17616\";s:20:\"original_revision_id\";s:5:\"17616\";s:17:\"operation_set_ids\";s:36:\"images_performance_and_seo_optimizer\";s:10:\"operations\";a:1:{i:0;s:11:\"tag_replace\";}}"],"_yoast_wpseo_primary_category":["36"],"_encloseme":["1"],"_yoast_wpseo_video_meta":["a:16:{s:2:\"id\";s:11:\"2dLRktIZrPk\";s:3:\"url\";s:41:\"https:\/\/www.youtube.com\/embed\/2dLRktIZrPk\";s:4:\"type\";s:7:\"youtube\";s:10:\"player_loc\";s:41:\"https:\/\/www.youtube.com\/embed\/2dLRktIZrPk\";s:13:\"thumbnail_loc\";s:80:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/2dlrktizrpk-1.jpg\";s:12:\"last_fetched\";i:1678439814;s:8:\"duration\";i:142;s:10:\"view_count\";s:3:\"162\";s:5:\"width\";i:480;s:6:\"height\";i:270;s:7:\"post_id\";i:17616;s:5:\"title\";s:64:\"Pepian o Pipian Verde con Pavo - Adriana&amp;#039;s Best Recipes\";s:16:\"publication_date\";s:25:\"2017-11-09T05:59:24+00:00\";s:11:\"description\";s:154:\"El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino.\";s:8:\"category\";s:4:\"Cena\";s:3:\"tag\";a:1:{i:0;s:6:\"Pepian\";}}"],"litespeed_vpi_list":["a:3:{i:0;s:37:\"ABRecipes-New-Logo-with-Trademark.jpg\";i:1;s:30:\"Green-Pepian-Turkey-Dinner.jpg\";i:2;s:36:\"Adriana-Martin-TACOS-23-683x1024.jpg\";}"],"_seopress_titles_desc":["El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino."],"_seopress_analysis_target_kw":["sous vide,Pepian"],"wprm_rating_count":["0"],"dpsp_share_options_json":["{\"custom_image\":{\"id\":\"\",\"src\":\"\"},\"custom_title\":\"\",\"custom_description\":\"\",\"custom_image_pinterest\":{\"id\":\"17631\",\"src\":\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-pepian-or-mole-verde-made-with-pumpkin-seeds-pepitas-epazote-and-cumin-seeds-roasted-serrano-peppers-tomatillos-and-garlic.-Paired-with-turkey-tenderloin.jpg\"},\"custom_description_pinterest\":\"El pepian o pipi\u00e1n cocinado con la t\u00e9cnica sous vide. La salsa est\u00e1 hecha con pepitas de calabaza y condimentos especiales como el epazote y el comino. El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Esta receta es corresponde a la cocina mexicana cl\u00e1sica.  #CocinaMexicana #pepiandepavo #pipian #moleverde\",\"custom_tweet\":\"El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Conoce los detalles. \"}"],"dpsp_networks_shares_json":["{\"facebook\":8,\"pinterest\":102,\"twitter\":0,\"yummly\":0,\"reddit\":0,\"buffer\":0,\"grow\":1}"],"wprm_rating_no_text_comments":["a:0:{}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}","a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:3:{i:0;s:10:\"core\/image\";i:1;s:14:\"core\/paragraph\";i:2;s:22:\"wp-recipe-maker\/recipe\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1784147418\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",1000,750,false],"thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-180x180.jpg",180,180,true],"medium":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",1000,750,false],"large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",1000,750,false],"1536x1536":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",1000,750,false],"2048x2048":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",1000,750,false],"wprm-metadata-1_1":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-500x500.jpg",500,500,true],"wprm-metadata-4_3":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-480x270.jpg",480,270,true],"rpwe-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-45x45.jpg",45,45,true],"mailchimp":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner-560x420.jpg",560,420,true],"web-stories-poster-portrait":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg",150,113,false]},"uagb_author_info":{"display_name":"Chef Adriana Martin","author_link":"https:\/\/www.adrianasbestrecipes.com\/es\/author\/adriana\/"},"uagb_comment_info":0,"uagb_excerpt":"El pepian o pipi\u00e1n tambi\u00e9n es llamado mole verde y es una salsa muy especial. Hecha con pepitas de calabaza y condimentos especiales como el epazote.","jetpack-related-posts":[{"id":17609,"url":"https:\/\/www.adrianasbestrecipes.com\/green-pepian-turkey-dinner\/","url_meta":{"origin":17616,"position":0},"title":"Green Pepian Turkey Dinner","author":"Chef Adriana Martin","date":"9 de noviembre de 2017","format":false,"excerpt":"Green pepian or mole verde made with pumpkin seeds (pepitas), epazote and cumin seeds, roasted serrano peppers, tomatillos and garlic. Paired with turkey tenderloin.","rel":"","context":"En \u00abCulture\u00bb","block_context":{"text":"Culture","link":"https:\/\/www.adrianasbestrecipes.com\/category\/culture\/"},"img":{"alt_text":"Pepian o Pipian Verde con Pavo","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/11\/Green-Pepian-Turkey-Dinner.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24946,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/salsa-verde-de-pepitas-de-calabaza\/","url_meta":{"origin":17616,"position":1},"title":"Salsa Verde de Pepitas de Calabaza","author":"Chef Adriana Martin","date":"27 de septiembre de 2018","format":false,"excerpt":"\u00a1Prepara la salsa verde de pepitas de calabaza es sencilla y deliciosa!","rel":"","context":"En \u00abCultura\u00bb","block_context":{"text":"Cultura","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cultura\/"},"img":{"alt_text":"Aut\u00e9ntica Salsa Verde de Pepitas de Calabaza","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Authentic-green-pepita-sauce.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9639,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pasta-otonal\/","url_meta":{"origin":17616,"position":2},"title":"Pasta Oto\u00f1al para el Men\u00fa de Thanksgiving","author":"Chef Adriana Martin","date":"11 de noviembre de 2016","format":false,"excerpt":"Receta f\u00e1cil para hacer pasta oto\u00f1al hecha con salsa marinara de ajo tostado, calabaza, chipotle, pepitas y queso fresco. Una deliciosa adici\u00f3n para el men\u00fa de Acci\u00f3n de Gracias.","rel":"","context":"En \u00abAlmuerzo\u00bb","block_context":{"text":"Almuerzo","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/almuerzo-es\/"},"img":{"alt_text":"Fall pasta for Thanksgiving has butternut squash, chipotle, pepitas and tomato sauce.","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/11\/Fall-Pasta-for-the-Thanksgiving-Menu.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13639,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/salsa-taquera-de-chile-cascabel\/","url_meta":{"origin":17616,"position":3},"title":"Salsa Taquera de Chile Cascabel","author":"Chef Adriana Martin","date":"20 de mayo de 2017","format":false,"excerpt":"La cocina mexicana se caracteriza por agregar sabor y texturas a sus platillos. Las salsas picantes como esta salsa taquera de chile cascabel son esenciales para disfrutar una experiencia con el aut\u00e9ntico de sabor de M\u00e9xico.","rel":"","context":"En \u00abCultura\u00bb","block_context":{"text":"Cultura","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cultura\/"},"img":{"alt_text":"Salsa Taquera de Chile Cascabel una Receta Sencilla","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/05\/Cascabel-Taquera-Sauce-and-Easy-Mexican-Recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/05\/Cascabel-Taquera-Sauce-and-Easy-Mexican-Recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/05\/Cascabel-Taquera-Sauce-and-Easy-Mexican-Recipe.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/05\/Cascabel-Taquera-Sauce-and-Easy-Mexican-Recipe.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":21235,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/batatas-al-chipotle-en-sous-vide\/","url_meta":{"origin":17616,"position":4},"title":"Batatas al Chipotle en Sous-Vide","author":"Chef Adriana Martin","date":"4 de junio de 2018","format":false,"excerpt":"Las mejores batatas al chipotle cocinadas a la perfecci\u00f3n en sous-vide. Listas en 30 minutos.","rel":"","context":"En \u00abCocina Sous Vide\u00bb","block_context":{"text":"Cocina Sous Vide","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cocina-sous-vide\/"},"img":{"alt_text":"Las mejores batatas al chipotle, una receta hecha en el sous-vide","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/06\/The-best-chipotle-butter-sweet-potatoes-recipe-for-sous-vide.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/06\/The-best-chipotle-butter-sweet-potatoes-recipe-for-sous-vide.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/06\/The-best-chipotle-butter-sweet-potatoes-recipe-for-sous-vide.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/06\/The-best-chipotle-butter-sweet-potatoes-recipe-for-sous-vide.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24160,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/pozole-verde-de-cerdo-instant-pot\/","url_meta":{"origin":17616,"position":5},"title":"Pozole Verde de Cerdo Instant Pot","author":"Chef Adriana Martin","date":"27 de septiembre de 2018","format":false,"excerpt":"Inspirada en la receta cl\u00e1sica del Pozole Verde, cocin\u00e9 una versi\u00f3n actualizada del Pozole Verde de Cerdo utilizando el Instant Pot en lugar de una olla a presi\u00f3n com\u00fan.","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"Pozole Verde de Cerdo cocinado en el Instant Pot","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/09\/Instant-Pot-Green-Pork-Pozole-Recipe.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/17616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/comments?post=17616"}],"version-history":[{"count":0,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/17616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media\/17634"}],"wp:attachment":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media?parent=17616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/categories?post=17616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/tags?post=17616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}