{"id":12458,"date":"2017-04-13T17:37:46","date_gmt":"2017-04-13T21:37:46","guid":{"rendered":"https:\/\/www.adrianasbestrecipes.com\/?p=12458\/"},"modified":"2017-06-13T02:28:45","modified_gmt":"2017-06-13T06:28:45","slug":"vinos-tintos-locations-wine","status":"publish","type":"post","link":"https:\/\/www.adrianasbestrecipes.com\/es\/vinos-tintos-locations-wine\/","title":{"rendered":"Vinos Tintos Locations Wine"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Esta es una colaboraci\u00f3n patrocinada por Vinos Tintos\u00a0<a href=\"https:\/\/www.facebook.com\/LocationsWine\/\" target=\"_blank\" rel=\"nofollow\">Locations<\/a> Wine y Balzac Communications. Todas las opiniones son solo m\u00edas. Esta publicaci\u00f3n est\u00e1 dirigida a mayores de 21 a\u00f1os.<\/em><\/p>\n<figure id=\"attachment_12461\" aria-describedby=\"caption-attachment-12461\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12461\" title=\"Vinos Tintos marca Locations Wine\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends.jpg\" alt=\"Vinos Tintos marca Locations Wine\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends-600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends-610x458.jpg 610w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-Red-Blends-560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12461\" class=\"wp-caption-text\">Vinos Tintos marca Locations Wine<\/figcaption><\/figure>\n<p>Locations Wine es una compa\u00f1\u00eda de vinos creada por Dave Phinney en el 2008\u00a0con el prop\u00f3sito de hacer el mejor <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/vino-rita-de-zarzamoras-y-habanero\/\">vino<\/a> posible con las mejores <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/lomo-de-cerdo-con-uvas\/\">uvas<\/a> de un pa\u00eds o lugar determinado. Pero esta idea y la meta de lograr este sue\u00f1o fue mas dif\u00edcil de lo que Dave pod\u00eda imaginar. Para lograr su objetivo, tuvo que viajar por todo el mundo y reunirse con due\u00f1os de vi\u00f1edos, viticultores, bodegas y fabricantes de vinos tintos de todo el mundo para hacer posible su visi\u00f3n. Mira\u00a0el video para que conozcas la historia de Locations Wine y la zaga de Dave Phinney por lograr su meta.<\/p>\n<p><iframe title=\"Locations Wine - Brand Video for Europe\" src=\"https:\/\/player.vimeo.com\/video\/205045966?dnt=1&amp;app_id=122963\" width=\"1200\" height=\"675\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe><\/p>\n<p>Dave Phinney y su equipo siempre est\u00e1n a la b\u00fasqueda de vi\u00f1edos de alta calidad y trabajar con <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/dando-gracias-a-los-agricultores\/\">agricultores<\/a> con visi\u00f3n futurista. Para Dave no existen reglas. Como creador de vinos tintos su meta es\u00a0representar con orgullo las mejores parcelas vitivin\u00edcolas de ese pa\u00eds o ubicaci\u00f3n en donde se producen las uvas que \u00e9l escoge para sus vinos tintos. Para luego combinar dichas parcelas y elaborar un vino que rinde homenaje al pa\u00eds de origen.<\/p>\n<figure id=\"attachment_12462\" aria-describedby=\"caption-attachment-12462\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12462\" title=\"Degustando Vinos Tintos Locations Wine\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines.jpg\" alt=\"Degustando Vinos Tintos Locations Wine\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines-600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines-610x458.jpg 610w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Wining-with-Locations-Wines-560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12462\" class=\"wp-caption-text\">Degustando Vinos Tintos Locations Wine<\/figcaption><\/figure>\n<p>En otras palabras, Locations Wine produce vinos tintos en todo el mundo y sin limitaci\u00f3n. Utilizando las mejores <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/el-ano-nuevo-y-las-tradiciones\/\">uvas<\/a> disponibles y produciendo no s\u00f3lo <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/vino-de-chocolate-y-cerezas\/\">vinos<\/a>\u00a0tintos, sino vinos blancos tambi\u00e9n. La mayor\u00eda de los vinos tintos que degust\u00e9 se embotellan en el lugar donde el vi\u00f1edo est\u00e1 localizado sin embargo hay algunos que se procesan y se embotellan en Barcelona.<\/p>\n<figure id=\"attachment_12463\" aria-describedby=\"caption-attachment-12463\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12463\" title=\"E-Espa\u00f1a vino tinto con una mezcla de uvas Garnacha, Tempranillo, Monastrell y Cari\u00f1ena\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo-.jpg\" alt=\"E-Espa\u00f1a vino tinto con una mezcla de uvas Garnacha, Tempranillo, Monastrell y Cari\u00f1ena\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo-.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo--300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo--150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo--600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo--610x458.jpg 610w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/E-is-for-Spain-and-a-red-blend-with-garnacha-and-tempranillo--560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12463\" class=\"wp-caption-text\">E-Espa\u00f1a vino tinto con una mezcla de uvas Garnacha, Tempranillo, Monastrell y Cari\u00f1ena<\/figcaption><\/figure>\n<p>La calidad de los vinos tintos de Locations Wine es muy buena, \u00e9ste no es el t\u00edpico\u00a0vino barato que se compra en el supermercado. Nuestro vino tinto favorito de Locations Wine es E-Espa\u00f1a. Este es un verdadero vino tinto espa\u00f1ol con una mezcla de uvas Garnacha, <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/celebrando-con-los-vinos-de-la-rioja\/\">Tempranillo<\/a>, Monastrell y Cari\u00f1ena. Este vino es sedoso con notas arom\u00e1ticas de pimienta blanca, tabaco y grosellas. Con sabor de ciruelas, cerezas negras y notas de vainilla. Este vino va muy bien con platos \u00a0espa\u00f1oles tradicionales como la <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/paella-3\/\">paella<\/a> o un buen <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/ensalada-de-filete-de-res\/\">filete<\/a>.<\/p>\n<figure id=\"attachment_12464\" aria-describedby=\"caption-attachment-12464\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12464\" title=\"F - Francia uno de los vinos tintos de Locations Wine\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg\" alt=\"F - Francia uno de los vinos tintos de Locations Wine\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-500x375.jpg 500w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-560x420.jpg 560w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-610x458.jpg 610w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12464\" class=\"wp-caption-text\">F - Francia vino tinto franc\u00e9s realmente maravilloso<\/figcaption><\/figure>\n<p>Nuestro segundo favorito es F-Francia. Un vino tinto con una mezcla de Garnacha del Rosell\u00f3n, Syrah del Valle del R\u00f3dano y variadas variedades de Burdeos. Todas nuestras regiones favoritas en donde se produce\u00a0el mejor vino tinto franc\u00e9s en el mundo. El bouquet es de un vino con cuerpo, con sabor de regaliz, grosellas negras y alcanfor. Un equilibrio perfecto y vibrante.<\/p>\n<figure id=\"attachment_12466\" aria-describedby=\"caption-attachment-12466\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12466\" title=\"Locations Wine I-Italia es una mezcla de uvas de Negroamaro y Nero d'Avola \" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine.jpg\" alt=\"Locations Wine I-Italia es una mezcla de uvas de Negroamaro y Nero d'Avola de la regi\u00f3n meridional de Puglia\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine-300x225.jpg 300w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine-150x113.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine-600x450.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine-610x458.jpg 610w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Feeling-better-with-an-Italian-red-from-Locations-Wine-560x420.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12466\" class=\"wp-caption-text\">Locations Wine I-Italia es una mezcla de uvas de Negroamaro y Nero d'Avola<\/figcaption><\/figure>\n<p>Los vinos tintos italianos est\u00e1n en nuestra lista preferidos y Locations Wine I-Italia es una mezcla de uvas de Negroamaro y Nero d'Avola de la regi\u00f3n meridional de Puglia combinado con uvas de Barbera de Piemonte del norte de Italia. Todas las regiones vitivin\u00edcolas mas grandes e importantes en donde se producen maravillosos vinos tintos italianos. Este vino tinto italiano de Locations Wine tiene notas de hierbas silvestres, regaliz, pieles de <a href=\"https:\/\/www.adrianasbestrecipes.com\/es\/ensalada-toscana-con-pan-y-tomates\/\">tomate<\/a>, aceitunas negras, grosellas rojas y negras, cerezas, especias de barbacoa y brasas ardientes. Perfecto para un fest\u00edn italiano agradable pero este vino tambi\u00e9n podr\u00eda combinar muy bien con comida mexicana.<\/p>\n<figure id=\"attachment_12467\" aria-describedby=\"caption-attachment-12467\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-12467\" title=\"Locations Wine es una compa\u00f1\u00eda de vinos creada por Dave Phinney en el 2008 con el prop\u00f3sito de hacer el mejor vino posible con las mejores uvas del mundo\" src=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location.jpg\" alt=\"Locations Wine es una compa\u00f1\u00eda de vinos creada por Dave Phinney en el 2008 con el prop\u00f3sito de hacer el mejor vino posible con las mejores uvas del mundo\" width=\"1000\" height=\"1333\" srcset=\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location.jpg 1000w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-225x300.jpg 225w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-768x1024.jpg 768w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-150x200.jpg 150w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-600x800.jpg 600w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-610x813.jpg 610w, https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/Locations-Wines-a-winery-created-by-Dave-Phinney-in-2008-with-the-simple-concept-of-making-the-best-possible-wine-from-a-given-country-or-location-560x746.jpg 560w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12467\" class=\"wp-caption-text\">Locations Wine es una compa\u00f1\u00eda de vinos creada por Dave Phinney en el 2008 con el prop\u00f3sito de hacer el mejor vino posible con las mejores uvas del mundo<\/figcaption><\/figure>\n<p style=\"text-align: center;\">Si te\u00a0gusta el buen vino tinto te recomiendo probar Locations Wine, te encantar\u00e1n cualesquiera de estos vinos tintos que degustamos.<\/p>\n<p><script type=\"text\/javascript\">\namzn_assoc_placement = \"adunit0\";\namzn_assoc_search_bar = \"true\";\namzn_assoc_search_bar_position = \"bottom\";\namzn_assoc_tracking_id = \"adrian092c-20\";\namzn_assoc_ad_mode = \"search\";\namzn_assoc_ad_type = \"smart\";\namzn_assoc_marketplace = \"amazon\";\namzn_assoc_region = \"US\";\namzn_assoc_title = \"Shop Related Products\";\namzn_assoc_default_search_phrase = \"wine\";\namzn_assoc_default_category = \"Grocery\";\namzn_assoc_linkid = \"be1edb4ecd806b78dd05e31d600b3655\";\namzn_assoc_default_browse_node = \"16310101\";\n<\/script><br \/>\n<script src=\"\/\/z-na.amazon-adsystem.com\/widgets\/onejs?MarketPlace=US\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n.<\/p>\n","protected":false},"author":2,"featured_media":12464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n","_seopress_robots_index":"","_seopress_analysis_target_kw":"vinos tintos","_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3538,57,513,3530],"tags":[],"class_list":["post-12458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","category-beverages-es","category-videos","category-vino","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_featured_media_url":"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg","spectra_custom_meta":{"_edit_lock":["1497335221:2"],"_edit_last":["2"],"_alp_processed":["1497335325"],"_et_monarch_override":[""],"_yoast_wpseo_focuskw_text_input":["vinos tintos"],"_yoast_wpseo_focuskw":["vinos tintos"],"_yoast_wpseo_linkdex":["99"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_primary_category":["3538"],"_thumbnail_id":["12464"],"_yoast_wpseo_metadesc":["Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n"],"_genesis_scripts_body_position":["bottom"],"_totes":["103"],"bitly_link":["http:\/\/bit.ly\/2E3CkH1"],"_google_plus_shares":["0"],"bitly_link_google_plus":["http:\/\/bit.ly\/2vGsDZO"],"_facebook_shares":["91"],"_pinterest_shares":["12"],"_buffer_shares":["0"],"_yummly_shares":["0"],"_twitter_shares":["0"],"_whatsapp_shares":["0"],"_flipboard_shares":["0"],"_mix_shares":["0"],"_email_shares":["0"],"_total_shares":["103"],"swp_pinterest_image_url":[""],"swp_open_graph_image_data":["false"],"swp_open_graph_image_url":[""],"bitly_link_facebook":["http:\/\/bit.ly\/2P9AU0C"],"bitly_link_twitter":["http:\/\/bit.ly\/2P9AVlc"],"bitly_link_mix":["http:\/\/bit.ly\/2tL80u7"],"bitly_link_buffer":["http:\/\/bit.ly\/2tNR2eu"],"bitly_link_flipboard":["http:\/\/bit.ly\/2tOBLtO"],"bitly_link_email":["http:\/\/bit.ly\/2tPTAIZ"],"bitly_link_whatsapp":["http:\/\/bit.ly\/2P88FiD"],"bitly_link_yummly":["http:\/\/bit.ly\/2vGsFAU"],"swp_cache_timestamp":["430982"],"dpsp_networks_shares":["a:7:{s:8:\"facebook\";i:91;s:9:\"pinterest\";i:12;s:7:\"twitter\";i:0;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;s:6:\"buffer\";i:0;s:4:\"grow\";i:1;}"],"dpsp_networks_shares_total":["104"],"dpsp_networks_shares_last_updated":["1643564404"],"dpsp_cache_shares_twitter_2":["0"],"dpsp_short_link_bitly":["a:14:{s:18:\"facebook_short_url\";s:21:\"http:\/\/bit.ly\/2G5Yxoa\";s:17:\"twitter_short_url\";s:21:\"http:\/\/bit.ly\/2G78D8c\";s:18:\"whatsapp_short_url\";s:21:\"http:\/\/bit.ly\/2G6nPCL\";s:16:\"yummly_short_url\";s:21:\"http:\/\/bit.ly\/2G78DFe\";s:15:\"email_short_url\";s:21:\"http:\/\/bit.ly\/2G5ua0Y\";s:13:\"mix_short_url\";s:21:\"http:\/\/bit.ly\/2VSAIqi\";s:19:\"flipboard_short_url\";s:21:\"http:\/\/bit.ly\/2IUiH5u\";s:18:\"linkedin_short_url\";s:21:\"http:\/\/bit.ly\/31o9Z5X\";s:16:\"reddit_short_url\";s:21:\"http:\/\/bit.ly\/2pqcdV6\";s:16:\"buffer_short_url\";s:21:\"http:\/\/bit.ly\/2MnJgSM\";s:18:\"telegram_short_url\";s:21:\"http:\/\/bit.ly\/2pw2Wux\";s:14:\"grow_short_url\";s:22:\"https:\/\/bit.ly\/3us6Cdt\";s:17:\"threads_short_url\";s:22:\"https:\/\/bit.ly\/45xe1LT\";s:18:\"mastodon_short_url\";s:22:\"https:\/\/bit.ly\/3VwLLoa\";}"],"_jetpack_related_posts_cache":["a:1:{s:32:\"37550b67d263a3ce789993dc25046c5f\";a:2:{s:7:\"expires\";i:1622292759;s:7:\"payload\";a:6:{i:0;a:1:{s:2:\"id\";i:4415;}i:1;a:1:{s:2:\"id\";i:27240;}i:2;a:1:{s:2:\"id\";i:7258;}i:3;a:1:{s:2:\"id\";i:25244;}i:4;a:1:{s:2:\"id\";i:3709;}i:5;a:1:{s:2:\"id\";i:17414;}}}}"],"dpsp_post_previous_urls":["a:1:{i:0;s:78:\"https:\/\/www.adrianasbestrecipes.com\/es\/2017\/04\/13\/vinos-tintos-locations-wine\/\";}"],"dpsp_networks_shares_previous_urls":["a:5:{s:8:\"facebook\";i:0;s:7:\"twitter\";i:0;s:9:\"pinterest\";i:1;s:6:\"yummly\";i:0;s:6:\"reddit\";i:0;}"],"_tbf_fix_details":["a:5:{s:6:\"fix_id\";s:4:\"5097\";s:19:\"changed_revision_id\";s:5:\"12458\";s:20:\"original_revision_id\";s:5:\"12458\";s:17:\"operation_set_ids\";s:36:\"images_performance_and_seo_optimizer\";s:10:\"operations\";a:1:{i:0;s:11:\"tag_replace\";}}"],"_yoast_wpseo_video_meta":["a:14:{s:2:\"id\";s:9:\"205045966\";s:4:\"type\";s:5:\"vimeo\";s:3:\"url\";s:27:\"https:\/\/vimeo.com\/205045966\";s:7:\"post_id\";i:12458;s:5:\"title\";s:61:\"Vinos Tintos Locations Wine - Adriana&amp;#039;s Best Recipes\";s:16:\"publication_date\";s:25:\"2017-04-13T21:37:46+00:00\";s:11:\"description\";s:158:\"Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n\";s:10:\"player_loc\";s:40:\"https:\/\/player.vimeo.com\/video\/205045966\";s:8:\"duration\";i:186;s:5:\"width\";i:1920;s:6:\"height\";i:1080;s:13:\"thumbnail_loc\";s:111:\"https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg\";s:8:\"category\";s:11:\"Agricultura\";s:3:\"tag\";a:1:{i:0;s:12:\"vinos tintos\";}}"],"litespeed_vpi_list":["a:3:{i:0;s:37:\"ABRecipes-New-Logo-with-Trademark.jpg\";i:1;s:48:\"F-from-France-makes-it-fun-to-drink-red-wine.jpg\";i:2;s:36:\"Adriana-Martin-TACOS-23-683x1024.jpg\";}"],"_seopress_titles_desc":["Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n"],"_seopress_analysis_target_kw":["vinos tintos"],"dpsp_networks_shares_json":["{\"facebook\":91,\"pinterest\":12,\"twitter\":0,\"yummly\":0,\"reddit\":0,\"buffer\":0,\"grow\":1}"],"wprm_rating_no_text_comments":["a:0:{}"],"copied_media_ids":["a:6:{i:0;i:220567;i:1;i:220568;i:2;i:220569;i:3;i:220570;i:4;i:220571;i:5;i:220572;}"],"referenced_media_ids":["a:1:{i:0;i:12464;}"],"_oembed_2fcc040fdf2f1a3aaf8c9738b04d9fc3":["<iframe title=\"Locations Wine - Brand Video for Europe\" src=\"https:\/\/player.vimeo.com\/video\/205045966?dnt=1&amp;app_id=122963\" width=\"868\" height=\"488\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>"],"_oembed_time_2fcc040fdf2f1a3aaf8c9738b04d9fc3":["1766085245"],"_oembed_3f5dbf96a3bd14f18725713dd89af2ee":["<iframe title=\"Locations Wine - Brand Video for Europe\" src=\"https:\/\/player.vimeo.com\/video\/205045966?dnt=1&amp;app_id=122963\" width=\"1200\" height=\"675\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>"],"_oembed_time_3f5dbf96a3bd14f18725713dd89af2ee":["1766228453"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:0:{}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778695482\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",1000,750,false],"thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-180x180.jpg",180,180,true],"medium":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",1000,750,false],"large":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",1000,750,false],"1536x1536":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",1000,750,false],"2048x2048":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",1000,750,false],"wprm-metadata-1_1":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-500x500.jpg",500,500,true],"wprm-metadata-4_3":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-480x270.jpg",480,270,true],"rpwe-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-45x45.jpg",45,45,true],"mailchimp":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine-560x420.jpg",560,420,true],"web-stories-poster-portrait":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",640,480,false],"web-stories-publisher-logo":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",96,72,false],"web-stories-thumbnail":["https:\/\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2017\/04\/F-from-France-makes-it-fun-to-drink-red-wine.jpg",150,113,false]},"uagb_author_info":{"display_name":"Chef Adriana Martin","author_link":"https:\/\/www.adrianasbestrecipes.com\/es\/author\/adriana\/"},"uagb_comment_info":0,"uagb_excerpt":"Locations Wine produce vinos tintos en todo el mundo. Utilizando las mejores uvas disponibles y produciendo no s\u00f3lo vinos tintos, sino vinos blancos tambi\u00e9n.","jetpack-related-posts":[{"id":4415,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/celebrando-con-los-vinos-de-la-rioja\/","url_meta":{"origin":12458,"position":0},"title":"Celebrando con los Vinos de la Rioja","author":"Chef Adriana Martin","date":"14 de noviembre de 2015","format":false,"excerpt":"Conoce los vinos de Espa\u00f1a","rel":"","context":"En \u00abBebidas y Cocteles\u00bb","block_context":{"text":"Bebidas y Cocteles","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/beverages-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/11\/This-year-I-am-planning-holiday-entertaining-with-Rioja-Wines-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/11\/This-year-I-am-planning-holiday-entertaining-with-Rioja-Wines-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/11\/This-year-I-am-planning-holiday-entertaining-with-Rioja-Wines-1-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3709,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/granita-de-moras-con-vino-chateau-la-paws\/","url_meta":{"origin":12458,"position":1},"title":"Granita de Moras con Vino Chateau La Paws","author":"Chef Adriana Martin","date":"23 de abril de 2015","format":false,"excerpt":"Brindando por una buena causa","rel":"","context":"En \u00abBebidas y Cocteles\u00bb","block_context":{"text":"Bebidas y Cocteles","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/beverages-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/04\/Chateau-La-Paws-Blueberry-Granita-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/04\/Chateau-La-Paws-Blueberry-Granita-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2015\/04\/Chateau-La-Paws-Blueberry-Granita-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27240,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/maridajes-con-vinos-italianos\/","url_meta":{"origin":12458,"position":2},"title":"Maridajes con Vinos Italianos","author":"Chef Adriana Martin","date":"6 de marzo de 2019","format":false,"excerpt":"Disfruta de maridajes con vinos italianos de Friuli, Toscana y Veneto. \u00a1Conoce los vinos italianos y experimenta La Dolce Vita! Inspirada por el reciente viaje que hice a Italia he recreado el men\u00fa y los maridajes con Pinot Grigio, Montepulciano d\u2019Abruzzo y Prosecco.","rel":"","context":"En \u00abCultura\u00bb","block_context":{"text":"Cultura","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cultura\/"},"img":{"alt_text":"Maridajes con vinos italianos","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/12\/Italian-Wine-Lovers-Menu-and-Pairings.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/12\/Italian-Wine-Lovers-Menu-and-Pairings.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/12\/Italian-Wine-Lovers-Menu-and-Pairings.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2018\/12\/Italian-Wine-Lovers-Menu-and-Pairings.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":770,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/filete-apasionado\/","url_meta":{"origin":12458,"position":3},"title":"Filete Apasionado","author":"Chef Adriana Martin","date":"27 de enero de 2013","format":false,"excerpt":"Disfruta de una cena para dos inspirada en el arte de la enolog\u00eda en el d\u00eda de San Valent\u00edn","rel":"","context":"En \u00abCena\u00bb","block_context":{"text":"Cena","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/cena-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2012\/08\/Steak-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2012\/08\/Steak-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2012\/08\/Steak-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2012\/08\/Steak-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1880,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/vino-de-chocolate-y-cerezas\/","url_meta":{"origin":12458,"position":4},"title":"Vino de Chocolate y Cerezas","author":"Chef Adriana Martin","date":"26 de agosto de 2013","format":false,"excerpt":"No hay nada como vino de chocolate y cerezas para disfrutar de la temporada","rel":"","context":"En \u00abPostres y Panader\u00eda\u00bb","block_context":{"text":"Postres y Panader\u00eda","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/postres\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2013\/08\/Chocolate-Wine-and-Cherries-Preparation-1800.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2013\/08\/Chocolate-Wine-and-Cherries-Preparation-1800.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2013\/08\/Chocolate-Wine-and-Cherries-Preparation-1800.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2013\/08\/Chocolate-Wine-and-Cherries-Preparation-1800.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7258,"url":"https:\/\/www.adrianasbestrecipes.com\/es\/vino-rita-de-zarzamoras-y-habanero\/","url_meta":{"origin":12458,"position":5},"title":"Vino Rita de Zarzamoras y Habanero","author":"Chef Adriana Martin","date":"7 de junio de 2016","format":false,"excerpt":"Hacer c\u00f3cteles artesanales en casa, como esta Vino Rita de Zarzamoras y Habanero es una manera creativa para celebrar este verano con vinos Sutter Home.","rel":"","context":"En \u00abBebidas y Cocteles\u00bb","block_context":{"text":"Bebidas y Cocteles","link":"https:\/\/www.adrianasbestrecipes.com\/es\/category\/beverages-es\/"},"img":{"alt_text":"Vino Rita de Zarzamoras y Habanero hecha con Sutter Home Sweet Red Wine","src":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/06\/Spicy-Blackberry-Wine-Rita-with-Sutter-Home-Sweet-Red-Wine.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/06\/Spicy-Blackberry-Wine-Rita-with-Sutter-Home-Sweet-Red-Wine.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/06\/Spicy-Blackberry-Wine-Rita-with-Sutter-Home-Sweet-Red-Wine.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.adrianasbestrecipes.com\/wp-content\/uploads\/2016\/06\/Spicy-Blackberry-Wine-Rita-with-Sutter-Home-Sweet-Red-Wine.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/12458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/comments?post=12458"}],"version-history":[{"count":0,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/posts\/12458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media\/12464"}],"wp:attachment":[{"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/media?parent=12458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/categories?post=12458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianasbestrecipes.com\/es\/wp-json\/wp\/v2\/tags?post=12458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}